{"id":227786,"date":"2021-09-15T15:15:47","date_gmt":"2021-09-15T18:15:47","guid":{"rendered":"http:\/\/triciclo.eco.br\/?p=227786"},"modified":"2024-10-25T13:52:09","modified_gmt":"2024-10-25T16:52:09","slug":"novas-recicla-pharmas-sao-instaladas-na-rede-de-farmacias-drogaria-sao-paulo","status":"publish","type":"post","link":"https:\/\/triciclo.eco.br\/en\/novas-recicla-pharmas-sao-instaladas-na-rede-de-farmacias-drogaria-sao-paulo\/","title":{"rendered":"Novas Recicla Pharmas s\u00e3o instaladas na rede de farm\u00e1cias Drogaria S\u00e3o Paulo"},"content":{"rendered":"<p>[et_pb_section fb_built=&#8221;1&#8243; admin_label=&#8221;section&#8221; _builder_version=&#8221;4.16&#8243; custom_padding=&#8221;0px|||||&#8221; global_colors_info=&#8221;{}&#8221; theme_builder_area=&#8221;post_content&#8221;][et_pb_row admin_label=&#8221;row&#8221; _builder_version=&#8221;4.16&#8243; background_size=&#8221;initial&#8221; background_position=&#8221;top_left&#8221; background_repeat=&#8221;repeat&#8221; min_height=&#8221;1042px&#8221; global_colors_info=&#8221;{}&#8221; theme_builder_area=&#8221;post_content&#8221;][et_pb_column type=&#8221;4_4&#8243; _builder_version=&#8221;4.16&#8243; custom_padding=&#8221;|||&#8221; global_colors_info=&#8221;{}&#8221; custom_padding__hover=&#8221;|||&#8221; theme_builder_area=&#8221;post_content&#8221;][et_pb_text admin_label=&#8221;Text&#8221; _builder_version=&#8221;4.20.2&#8243; header_2_font_size=&#8221;25px&#8221; header_2_line_height=&#8221;1.2em&#8221; header_4_line_height=&#8221;1.4em&#8221; background_size=&#8221;initial&#8221; background_position=&#8221;top_left&#8221; background_repeat=&#8221;repeat&#8221; min_height=&#8221;958px&#8221; hover_enabled=&#8221;0&#8243; global_colors_info=&#8221;{}&#8221; theme_builder_area=&#8221;post_content&#8221; sticky_enabled=&#8221;0&#8243;]<\/p>\n<h2 style=\"text-align: center;\"><b>Novas Recicla Pharmas s\u00e3o instaladas na rede de farm\u00e1cias Drogaria S\u00e3o Paulo<\/b><\/h2>\n<p style=\"text-align: center;\"><span style=\"font-weight: 400;\">\u00a0<\/span><\/p>\n<h4 style=\"text-align: center;\"><b><i>Em conjunto com a L\u2019Oreal, Triciclo oferece descarte correto para res\u00edduos de classe farmac\u00eautica<\/i><\/b><\/h4>\n<p><b><\/b><\/p>\n<p style=\"text-align: center;\"><span style=\"font-size: medium;\"><b>Medicamentos vencidos, em desuso e suas embalagens poder\u00e3o ser depositados na Recicla Pharma com ganho e troca das tricoins (pontos Triciclo) por benef\u00edcios e mais uma promo\u00e7\u00e3o da parceria.<\/b><\/span><\/p>\n<p><b><i><\/i><\/b><\/p>\n<p><b><i> <\/i><\/b><\/p>\n<p><b><i><\/i><\/b><\/p>\n<h4 style=\"text-align: center;\"><span style=\"font-size: 14px; text-align: left; color: #666666;\">\u00a0<\/span><\/h4>\n<p style=\"text-align: justify;\"><b>S\u00e3o Paulo, 5 de agosto &#8211;<\/b><span style=\"font-weight: 400;\">\u00a0 A Triciclo est\u00e1 inovando cada dia mais no recebimento e reciclagem de res\u00edduos sem mais utiliza\u00e7\u00e3o e oferecendo novas solu\u00e7\u00f5es para descartes incorretos. Por isso, em conjunto com a L\u2019Oreal, dez novas instala\u00e7\u00f5es de Recicla Pharmas ocorreram na rede de farm\u00e1cias Drogaria S\u00e3o Paulo, por toda capital.<\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"font-weight: 400;\">Esse novo produto recebe rem\u00e9dios vencidos ou em desuso e suas embalagens. Res\u00edduos cujo descarte \u00e9, muitas vezes, inapropriado para o meio-ambiente.<\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"font-weight: 400;\">A colabora\u00e7\u00e3o oferece com uma nova promo\u00e7\u00e3o: cada reciclagem d\u00e1 direito a um voucher de 15% de desconto nos produtos <\/span><a href=\"https:\/\/www.garnier.com.br\/\"><span style=\"font-weight: 400;\">Garnier<\/span><\/a><span style=\"font-weight: 400;\"> e <\/span><a href=\"https:\/\/www.loreal.com\/pt-br\/brazil\/\"><span style=\"font-weight: 400;\">L\u2019Oreal <\/span><\/a><span style=\"font-weight: 400;\">Paris Facial via compras no site da <\/span><a href=\"http:\/\/www.drogariasaopaulo.com.br\/\"><span style=\"font-weight: 400;\">Drogaria S\u00e3o Paulo<\/span><\/a><span style=\"font-weight: 400;\">.<\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"font-weight: 400;\">No contexto da reciclagem, a Triciclo procede com variadas op\u00e7\u00f5es de descarte e reaproveitamento de materiais dom\u00e9sticos acumulados com b\u00f4nus de lucro de cunho social, econ\u00f4mico e sustent\u00e1vel.<\/span><\/p>\n<p>&nbsp;<\/p>\n<p><span style=\"font-weight: 400;\"><\/span><\/p>\n<p>&nbsp;<\/p>\n<p><b>Informa\u00e7\u00f5es \u00e0 imprensa<\/b><br \/><span style=\"font-weight: 400;\">Lenita Medeiros<br \/>lenita@triciclo.eco.br<br \/>(11) 2362-8424<br \/>(11) 2362-8475<\/span><\/p>\n<p>[\/et_pb_text][\/et_pb_column][\/et_pb_row][\/et_pb_section]<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Novas Recicla Pharmas s\u00e3o instaladas na rede de farm\u00e1cias Drogaria S\u00e3o Paulo \u00a0 Em conjunto com a L\u2019Oreal, Triciclo oferece descarte correto para res\u00edduos de classe farmac\u00eautica Medicamentos vencidos, em desuso e suas embalagens poder\u00e3o ser depositados na Recicla Pharma com ganho e troca das tricoins (pontos Triciclo) por benef\u00edcios e mais uma promo\u00e7\u00e3o da [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":227822,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_et_pb_use_builder":"on","_et_pb_old_content":"<h2 style=\"text-align: center;\"><b>Rede de supermercados Bramil adquire duas Retorna Machines para instala\u00e7\u00e3o em dois estabelecimentos da franquia<\/b><\/h2>\r\n<p style=\"text-align: center;\"><span style=\"font-weight: 400;\">\u00a0<\/span><\/p>\r\n\r\n<h4 style=\"text-align: center;\"><b><i>Novidade para clientes e moradores das cidades de Itaipava e Tr\u00eas Rios, Retorna Machine cria est\u00edmulo \u00e0 reciclagem<\/i><\/b><\/h4>\r\n<span style=\"font-weight: 400;\">\u00a0<\/span>\r\n\r\n<b>S\u00e3o Paulo, 01 de julho de 2021 \u2013 <\/b><span style=\"font-weight: 400;\">O m\u00eas come\u00e7a com novidades para a <a href=\"https:\/\/www.bramil.com.br\/\" target=\"_blank\" rel=\"noopener noreferrer\">Bramil Supermercados<\/a>: duas Retorna Machines ganham espa\u00e7o nos estabelecimentos do Rio de Janeiro, nas cidades de Itaipava e Tr\u00eas Rios.<\/span>\r\n\r\n<span style=\"font-weight: 400;\">O Grupo Mil\u00a0 \u00e9\u00a0 pioneiro no interior carioca a contar com os equipamentos Triciclo e inovam na quest\u00e3o da sustentabilidade. O foco n\u00e3o muda: diminui\u00e7\u00e3o de res\u00edduos s\u00f3lidos e preserva\u00e7\u00e3o do meio ambiente, al\u00e9m de melhorar quest\u00f5es sociais pelos benef\u00edcios que o Programa Triciclo de Fidelidade proporciona atrav\u00e9s das RMs.<\/span>\r\n\r\n<span style=\"font-weight: 400;\">\u201cEsses res\u00edduos, que precisam estar devidamente limpos, poder\u00e3o ser depositados diretamente nas m\u00e1quinas. Ao fazerem isso, al\u00e9m de estarem ajudando na melhoria das condi\u00e7\u00f5es ambientais e de sustentabilidade de sua regi\u00e3o, os consumidores tamb\u00e9m participar\u00e3o de um programa de benef\u00edcios, nos quais de acordo com os materiais descartados na m\u00e1quina, ganhar\u00e3o pontos para troca ou aquisi\u00e7\u00e3o de produtos e mercadorias nas lojas das empresas do Grupo Mil\u201d, explicou Anderson Oliveira, integrante do grupo e respons\u00e1vel pelo projeto.<\/span>\r\n\r\n<span style=\"font-weight: 400;\">Cada vez mais novas empresas est\u00e3o se tornando conscientes da responsabilidade ambiental e social que possuem como parte do gerenciamento e resultado dos seus neg\u00f3cios. A Triciclo tem um papel fundamental ao oferecer solu\u00e7\u00f5es a esses empreendedores que est\u00e3o iniciando sua jornada para garantir um futuro melhor.<\/span>\r\n\r\n\u00a0\r\n\r\n<b>Informa\u00e7\u00f5es \u00e0 imprensa<\/b>\r\n<span style=\"font-weight: 400;\">Lenita Medeiros\r\nlenita@wp-triciclo.azurewebsites.net\r\n(11) 2362-8424\r\n(11) 2362-8475<\/span>","_et_gb_content_width":"","_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_memberships_contains_paid_content":false,"footnotes":""},"categories":[8],"tags":[],"class_list":["post-227786","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-blog"],"aioseo_notices":[],"aioseo_head":"\n\t\t<!-- All in One SEO 5.0.0.1 - aioseo.com -->\n\t<meta name=\"description\" content=\"Novas Recicla Pharmas s\u00e3o instaladas na rede de farm\u00e1cias Drogaria S\u00e3o Paulo Em conjunto com a L\u2019Oreal, Triciclo oferece descarte correto para res\u00edduos de classe farmac\u00eautica Medicamentos vencidos, em desuso e suas embalagens poder\u00e3o ser depositados na Recicla Pharma com ganho e troca das tricoins (pontos Triciclo) por benef\u00edcios e mais uma promo\u00e7\u00e3o da\" \/>\n\t<meta name=\"robots\" content=\"max-image-preview:large\" \/>\n\t<meta name=\"author\" content=\"Triciclo\"\/>\n\t<link rel=\"canonical\" href=\"https:\/\/triciclo.eco.br\/en\/novas-recicla-pharmas-sao-instaladas-na-rede-de-farmacias-drogaria-sao-paulo\/\" \/>\n\t<meta name=\"generator\" content=\"All in One SEO (AIOSEO) 5.0.0.1\" \/>\n\t\t<meta property=\"og:locale\" content=\"en_US\" \/>\n\t\t<meta property=\"og:site_name\" content=\"Ambipar Triciclo - Solu\u00e7\u00f5es Sustent\u00e1veis\" \/>\n\t\t<meta property=\"og:type\" content=\"article\" \/>\n\t\t<meta property=\"og:title\" content=\"Novas Recicla Pharmas s\u00e3o instaladas na rede de farm\u00e1cias Drogaria S\u00e3o Paulo - Ambipar Triciclo\" \/>\n\t\t<meta property=\"og:description\" content=\"Novas Recicla Pharmas s\u00e3o instaladas na rede de farm\u00e1cias Drogaria S\u00e3o Paulo Em conjunto com a L\u2019Oreal, Triciclo oferece descarte correto para res\u00edduos de classe farmac\u00eautica Medicamentos vencidos, em desuso e suas embalagens poder\u00e3o ser depositados na Recicla Pharma com ganho e troca das tricoins (pontos Triciclo) por benef\u00edcios e mais uma promo\u00e7\u00e3o da\" \/>\n\t\t<meta property=\"og:url\" content=\"https:\/\/triciclo.eco.br\/en\/novas-recicla-pharmas-sao-instaladas-na-rede-de-farmacias-drogaria-sao-paulo\/\" \/>\n\t\t<meta property=\"og:image\" content=\"https:\/\/triciclo.eco.br\/wp-content\/uploads\/2023\/08\/triciclo-logo-1.png\" \/>\n\t\t<meta property=\"og:image:secure_url\" content=\"https:\/\/triciclo.eco.br\/wp-content\/uploads\/2023\/08\/triciclo-logo-1.png\" \/>\n\t\t<meta property=\"og:image:width\" content=\"200\" \/>\n\t\t<meta property=\"og:image:height\" content=\"200\" \/>\n\t\t<meta property=\"article:published_time\" content=\"2021-09-15T18:15:47+00:00\" \/>\n\t\t<meta property=\"article:modified_time\" content=\"2024-10-25T16:52:09+00:00\" \/>\n\t\t<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/ambipar.triciclo\" \/>\n\t\t<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n\t\t<meta name=\"twitter:site\" content=\"@AmbiparTriciclo\" \/>\n\t\t<meta name=\"twitter:title\" content=\"Novas Recicla Pharmas s\u00e3o instaladas na rede de farm\u00e1cias Drogaria S\u00e3o Paulo - Ambipar Triciclo\" \/>\n\t\t<meta name=\"twitter:description\" content=\"Novas Recicla Pharmas s\u00e3o instaladas na rede de farm\u00e1cias Drogaria S\u00e3o Paulo Em conjunto com a L\u2019Oreal, Triciclo oferece descarte correto para res\u00edduos de classe farmac\u00eautica Medicamentos vencidos, em desuso e suas embalagens poder\u00e3o ser depositados na Recicla Pharma com ganho e troca das tricoins (pontos Triciclo) por benef\u00edcios e mais uma promo\u00e7\u00e3o da\" \/>\n\t\t<meta name=\"twitter:creator\" content=\"@AmbiparTriciclo\" \/>\n\t\t<meta name=\"twitter:image\" content=\"https:\/\/triciclo.eco.br\/wp-content\/uploads\/2023\/08\/Triciclo.jpg\" \/>\n\t\t<script type=\"application\/ld+json\" class=\"aioseo-schema\">\n\t\t\t{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"BlogPosting\",\"@id\":\"https:\\\/\\\/triciclo.eco.br\\\/en\\\/novas-recicla-pharmas-sao-instaladas-na-rede-de-farmacias-drogaria-sao-paulo\\\/#blogposting\",\"name\":\"Novas Recicla Pharmas s\\u00e3o instaladas na rede de farm\\u00e1cias Drogaria S\\u00e3o Paulo - Ambipar Triciclo\",\"headline\":\"Novas Recicla Pharmas s\\u00e3o instaladas na rede de farm\\u00e1cias Drogaria S\\u00e3o Paulo\",\"author\":{\"@id\":\"https:\\\/\\\/triciclo.eco.br\\\/en\\\/author\\\/triciclo\\\/#author\"},\"publisher\":{\"@id\":\"https:\\\/\\\/triciclo.eco.br\\\/en\\\/#organization\"},\"image\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/triciclo.eco.br\\\/wp-content\\\/uploads\\\/2021\\\/09\\\/Case-RP-LOreal-1.jpg\",\"width\":1200,\"height\":720},\"datePublished\":\"2021-09-15T15:15:47-03:00\",\"dateModified\":\"2024-10-25T13:52:09-03:00\",\"inLanguage\":\"en-US\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/triciclo.eco.br\\\/en\\\/novas-recicla-pharmas-sao-instaladas-na-rede-de-farmacias-drogaria-sao-paulo\\\/#webpage\"},\"isPartOf\":{\"@id\":\"https:\\\/\\\/triciclo.eco.br\\\/en\\\/novas-recicla-pharmas-sao-instaladas-na-rede-de-farmacias-drogaria-sao-paulo\\\/#webpage\"},\"articleSection\":\"Blog\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/triciclo.eco.br\\\/en\\\/novas-recicla-pharmas-sao-instaladas-na-rede-de-farmacias-drogaria-sao-paulo\\\/#breadcrumblist\",\"itemListElement\":[{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/triciclo.eco.br\\\/en#listItem\",\"position\":1,\"name\":\"In\\u00edcio\",\"item\":\"https:\\\/\\\/triciclo.eco.br\\\/en\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/triciclo.eco.br\\\/en\\\/category\\\/blog\\\/#listItem\",\"name\":\"Blog\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/triciclo.eco.br\\\/en\\\/category\\\/blog\\\/#listItem\",\"position\":2,\"name\":\"Blog\",\"item\":\"https:\\\/\\\/triciclo.eco.br\\\/en\\\/category\\\/blog\\\/\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/triciclo.eco.br\\\/en\\\/novas-recicla-pharmas-sao-instaladas-na-rede-de-farmacias-drogaria-sao-paulo\\\/#listItem\",\"name\":\"Novas Recicla Pharmas s\\u00e3o instaladas na rede de farm\\u00e1cias Drogaria S\\u00e3o Paulo\"},\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/triciclo.eco.br\\\/en#listItem\",\"name\":\"In\\u00edcio\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/triciclo.eco.br\\\/en\\\/novas-recicla-pharmas-sao-instaladas-na-rede-de-farmacias-drogaria-sao-paulo\\\/#listItem\",\"position\":3,\"name\":\"Novas Recicla Pharmas s\\u00e3o instaladas na rede de farm\\u00e1cias Drogaria S\\u00e3o Paulo\",\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/triciclo.eco.br\\\/en\\\/category\\\/blog\\\/#listItem\",\"name\":\"Blog\"}}]},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/triciclo.eco.br\\\/en\\\/#organization\",\"name\":\"Ambipar Triciclo Solu\\u00e7\\u00f5es Sustent\\u00e1veis\",\"description\":\"Solu\\u00e7\\u00f5es Sustent\\u00e1veis\",\"url\":\"https:\\\/\\\/triciclo.eco.br\\\/en\\\/\",\"telephone\":\"+551134295050\",\"logo\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/triciclo.eco.br\\\/wp-content\\\/uploads\\\/2023\\\/08\\\/Triciclo.jpg\",\"@id\":\"https:\\\/\\\/triciclo.eco.br\\\/en\\\/novas-recicla-pharmas-sao-instaladas-na-rede-de-farmacias-drogaria-sao-paulo\\\/#organizationLogo\",\"width\":113,\"height\":113},\"image\":{\"@id\":\"https:\\\/\\\/triciclo.eco.br\\\/en\\\/novas-recicla-pharmas-sao-instaladas-na-rede-de-farmacias-drogaria-sao-paulo\\\/#organizationLogo\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/ambipar.triciclo\",\"https:\\\/\\\/twitter.com\\\/AmbiparTriciclo\",\"https:\\\/\\\/www.instagram.com\\\/triciclo_retornamachine\\\/\",\"https:\\\/\\\/www.youtube.com\\\/@TricicloSolucoesSustentaveis\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/triciclo-solues-sustentveis\\\/\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/triciclo.eco.br\\\/en\\\/author\\\/triciclo\\\/#author\",\"url\":\"https:\\\/\\\/triciclo.eco.br\\\/en\\\/author\\\/triciclo\\\/\",\"name\":\"Triciclo\",\"image\":{\"@type\":\"ImageObject\",\"@id\":\"https:\\\/\\\/triciclo.eco.br\\\/en\\\/novas-recicla-pharmas-sao-instaladas-na-rede-de-farmacias-drogaria-sao-paulo\\\/#authorImage\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/8031027e39acb0f958577a55663464ac1cd1ffb991a23bf69b3ffbe38b0ecfbf?s=96&d=mm&r=g\",\"width\":96,\"height\":96,\"caption\":\"Triciclo\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/triciclo.eco.br\\\/en\\\/novas-recicla-pharmas-sao-instaladas-na-rede-de-farmacias-drogaria-sao-paulo\\\/#webpage\",\"url\":\"https:\\\/\\\/triciclo.eco.br\\\/en\\\/novas-recicla-pharmas-sao-instaladas-na-rede-de-farmacias-drogaria-sao-paulo\\\/\",\"name\":\"Novas Recicla Pharmas s\\u00e3o instaladas na rede de farm\\u00e1cias Drogaria S\\u00e3o Paulo - Ambipar Triciclo\",\"description\":\"Novas Recicla Pharmas s\\u00e3o instaladas na rede de farm\\u00e1cias Drogaria S\\u00e3o Paulo Em conjunto com a L\\u2019Oreal, Triciclo oferece descarte correto para res\\u00edduos de classe farmac\\u00eautica Medicamentos vencidos, em desuso e suas embalagens poder\\u00e3o ser depositados na Recicla Pharma com ganho e troca das tricoins (pontos Triciclo) por benef\\u00edcios e mais uma promo\\u00e7\\u00e3o da\",\"inLanguage\":\"en-US\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/triciclo.eco.br\\\/en\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/triciclo.eco.br\\\/en\\\/novas-recicla-pharmas-sao-instaladas-na-rede-de-farmacias-drogaria-sao-paulo\\\/#breadcrumblist\"},\"author\":{\"@id\":\"https:\\\/\\\/triciclo.eco.br\\\/en\\\/author\\\/triciclo\\\/#author\"},\"creator\":{\"@id\":\"https:\\\/\\\/triciclo.eco.br\\\/en\\\/author\\\/triciclo\\\/#author\"},\"image\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/triciclo.eco.br\\\/wp-content\\\/uploads\\\/2021\\\/09\\\/Case-RP-LOreal-1.jpg\",\"@id\":\"https:\\\/\\\/triciclo.eco.br\\\/en\\\/novas-recicla-pharmas-sao-instaladas-na-rede-de-farmacias-drogaria-sao-paulo\\\/#mainImage\",\"width\":1200,\"height\":720},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/triciclo.eco.br\\\/en\\\/novas-recicla-pharmas-sao-instaladas-na-rede-de-farmacias-drogaria-sao-paulo\\\/#mainImage\"},\"datePublished\":\"2021-09-15T15:15:47-03:00\",\"dateModified\":\"2024-10-25T13:52:09-03:00\"},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/triciclo.eco.br\\\/en\\\/#website\",\"url\":\"https:\\\/\\\/triciclo.eco.br\\\/en\\\/\",\"name\":\"Ambipar Triciclo\",\"alternateName\":\"Triciclo\",\"description\":\"Solu\\u00e7\\u00f5es Sustent\\u00e1veis\",\"inLanguage\":\"en-US\",\"publisher\":{\"@id\":\"https:\\\/\\\/triciclo.eco.br\\\/en\\\/#organization\"}}]}\n\t\t<\/script>\n\t\t<!-- All in One SEO -->\n\n","aioseo_head_json":{"title":"Novas Recicla Pharmas s\u00e3o instaladas na rede de farm\u00e1cias Drogaria S\u00e3o Paulo - Ambipar Triciclo","description":"Novas Recicla Pharmas s\u00e3o instaladas na rede de farm\u00e1cias Drogaria S\u00e3o Paulo Em conjunto com a L\u2019Oreal, Triciclo oferece descarte correto para res\u00edduos de classe farmac\u00eautica Medicamentos vencidos, em desuso e suas embalagens poder\u00e3o ser depositados na Recicla Pharma com ganho e troca das tricoins (pontos Triciclo) por benef\u00edcios e mais uma promo\u00e7\u00e3o da","canonical_url":"https:\/\/triciclo.eco.br\/en\/novas-recicla-pharmas-sao-instaladas-na-rede-de-farmacias-drogaria-sao-paulo\/","robots":"max-image-preview:large","keywords":"","webmasterTools":{"miscellaneous":""},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"BlogPosting","@id":"https:\/\/triciclo.eco.br\/en\/novas-recicla-pharmas-sao-instaladas-na-rede-de-farmacias-drogaria-sao-paulo\/#blogposting","name":"Novas Recicla Pharmas s\u00e3o instaladas na rede de farm\u00e1cias Drogaria S\u00e3o Paulo - Ambipar Triciclo","headline":"Novas Recicla Pharmas s\u00e3o instaladas na rede de farm\u00e1cias Drogaria S\u00e3o Paulo","author":{"@id":"https:\/\/triciclo.eco.br\/en\/author\/triciclo\/#author"},"publisher":{"@id":"https:\/\/triciclo.eco.br\/en\/#organization"},"image":{"@type":"ImageObject","url":"https:\/\/triciclo.eco.br\/wp-content\/uploads\/2021\/09\/Case-RP-LOreal-1.jpg","width":1200,"height":720},"datePublished":"2021-09-15T15:15:47-03:00","dateModified":"2024-10-25T13:52:09-03:00","inLanguage":"en-US","mainEntityOfPage":{"@id":"https:\/\/triciclo.eco.br\/en\/novas-recicla-pharmas-sao-instaladas-na-rede-de-farmacias-drogaria-sao-paulo\/#webpage"},"isPartOf":{"@id":"https:\/\/triciclo.eco.br\/en\/novas-recicla-pharmas-sao-instaladas-na-rede-de-farmacias-drogaria-sao-paulo\/#webpage"},"articleSection":"Blog"},{"@type":"BreadcrumbList","@id":"https:\/\/triciclo.eco.br\/en\/novas-recicla-pharmas-sao-instaladas-na-rede-de-farmacias-drogaria-sao-paulo\/#breadcrumblist","itemListElement":[{"@type":"ListItem","@id":"https:\/\/triciclo.eco.br\/en#listItem","position":1,"name":"In\u00edcio","item":"https:\/\/triciclo.eco.br\/en","nextItem":{"@type":"ListItem","@id":"https:\/\/triciclo.eco.br\/en\/category\/blog\/#listItem","name":"Blog"}},{"@type":"ListItem","@id":"https:\/\/triciclo.eco.br\/en\/category\/blog\/#listItem","position":2,"name":"Blog","item":"https:\/\/triciclo.eco.br\/en\/category\/blog\/","nextItem":{"@type":"ListItem","@id":"https:\/\/triciclo.eco.br\/en\/novas-recicla-pharmas-sao-instaladas-na-rede-de-farmacias-drogaria-sao-paulo\/#listItem","name":"Novas Recicla Pharmas s\u00e3o instaladas na rede de farm\u00e1cias Drogaria S\u00e3o Paulo"},"previousItem":{"@type":"ListItem","@id":"https:\/\/triciclo.eco.br\/en#listItem","name":"In\u00edcio"}},{"@type":"ListItem","@id":"https:\/\/triciclo.eco.br\/en\/novas-recicla-pharmas-sao-instaladas-na-rede-de-farmacias-drogaria-sao-paulo\/#listItem","position":3,"name":"Novas Recicla Pharmas s\u00e3o instaladas na rede de farm\u00e1cias Drogaria S\u00e3o Paulo","previousItem":{"@type":"ListItem","@id":"https:\/\/triciclo.eco.br\/en\/category\/blog\/#listItem","name":"Blog"}}]},{"@type":"Organization","@id":"https:\/\/triciclo.eco.br\/en\/#organization","name":"Ambipar Triciclo Solu\u00e7\u00f5es Sustent\u00e1veis","description":"Solu\u00e7\u00f5es Sustent\u00e1veis","url":"https:\/\/triciclo.eco.br\/en\/","telephone":"+551134295050","logo":{"@type":"ImageObject","url":"https:\/\/triciclo.eco.br\/wp-content\/uploads\/2023\/08\/Triciclo.jpg","@id":"https:\/\/triciclo.eco.br\/en\/novas-recicla-pharmas-sao-instaladas-na-rede-de-farmacias-drogaria-sao-paulo\/#organizationLogo","width":113,"height":113},"image":{"@id":"https:\/\/triciclo.eco.br\/en\/novas-recicla-pharmas-sao-instaladas-na-rede-de-farmacias-drogaria-sao-paulo\/#organizationLogo"},"sameAs":["https:\/\/www.facebook.com\/ambipar.triciclo","https:\/\/twitter.com\/AmbiparTriciclo","https:\/\/www.instagram.com\/triciclo_retornamachine\/","https:\/\/www.youtube.com\/@TricicloSolucoesSustentaveis","https:\/\/www.linkedin.com\/company\/triciclo-solues-sustentveis\/"]},{"@type":"Person","@id":"https:\/\/triciclo.eco.br\/en\/author\/triciclo\/#author","url":"https:\/\/triciclo.eco.br\/en\/author\/triciclo\/","name":"Triciclo","image":{"@type":"ImageObject","@id":"https:\/\/triciclo.eco.br\/en\/novas-recicla-pharmas-sao-instaladas-na-rede-de-farmacias-drogaria-sao-paulo\/#authorImage","url":"https:\/\/secure.gravatar.com\/avatar\/8031027e39acb0f958577a55663464ac1cd1ffb991a23bf69b3ffbe38b0ecfbf?s=96&d=mm&r=g","width":96,"height":96,"caption":"Triciclo"}},{"@type":"WebPage","@id":"https:\/\/triciclo.eco.br\/en\/novas-recicla-pharmas-sao-instaladas-na-rede-de-farmacias-drogaria-sao-paulo\/#webpage","url":"https:\/\/triciclo.eco.br\/en\/novas-recicla-pharmas-sao-instaladas-na-rede-de-farmacias-drogaria-sao-paulo\/","name":"Novas Recicla Pharmas s\u00e3o instaladas na rede de farm\u00e1cias Drogaria S\u00e3o Paulo - Ambipar Triciclo","description":"Novas Recicla Pharmas s\u00e3o instaladas na rede de farm\u00e1cias Drogaria S\u00e3o Paulo Em conjunto com a L\u2019Oreal, Triciclo oferece descarte correto para res\u00edduos de classe farmac\u00eautica Medicamentos vencidos, em desuso e suas embalagens poder\u00e3o ser depositados na Recicla Pharma com ganho e troca das tricoins (pontos Triciclo) por benef\u00edcios e mais uma promo\u00e7\u00e3o da","inLanguage":"en-US","isPartOf":{"@id":"https:\/\/triciclo.eco.br\/en\/#website"},"breadcrumb":{"@id":"https:\/\/triciclo.eco.br\/en\/novas-recicla-pharmas-sao-instaladas-na-rede-de-farmacias-drogaria-sao-paulo\/#breadcrumblist"},"author":{"@id":"https:\/\/triciclo.eco.br\/en\/author\/triciclo\/#author"},"creator":{"@id":"https:\/\/triciclo.eco.br\/en\/author\/triciclo\/#author"},"image":{"@type":"ImageObject","url":"https:\/\/triciclo.eco.br\/wp-content\/uploads\/2021\/09\/Case-RP-LOreal-1.jpg","@id":"https:\/\/triciclo.eco.br\/en\/novas-recicla-pharmas-sao-instaladas-na-rede-de-farmacias-drogaria-sao-paulo\/#mainImage","width":1200,"height":720},"primaryImageOfPage":{"@id":"https:\/\/triciclo.eco.br\/en\/novas-recicla-pharmas-sao-instaladas-na-rede-de-farmacias-drogaria-sao-paulo\/#mainImage"},"datePublished":"2021-09-15T15:15:47-03:00","dateModified":"2024-10-25T13:52:09-03:00"},{"@type":"WebSite","@id":"https:\/\/triciclo.eco.br\/en\/#website","url":"https:\/\/triciclo.eco.br\/en\/","name":"Ambipar Triciclo","alternateName":"Triciclo","description":"Solu\u00e7\u00f5es Sustent\u00e1veis","inLanguage":"en-US","publisher":{"@id":"https:\/\/triciclo.eco.br\/en\/#organization"}}]},"og:locale":"en_US","og:site_name":"Ambipar Triciclo - Solu\u00e7\u00f5es Sustent\u00e1veis","og:type":"article","og:title":"Novas Recicla Pharmas s\u00e3o instaladas na rede de farm\u00e1cias Drogaria S\u00e3o Paulo - Ambipar Triciclo","og:description":"Novas Recicla Pharmas s\u00e3o instaladas na rede de farm\u00e1cias Drogaria S\u00e3o Paulo Em conjunto com a L\u2019Oreal, Triciclo oferece descarte correto para res\u00edduos de classe farmac\u00eautica Medicamentos vencidos, em desuso e suas embalagens poder\u00e3o ser depositados na Recicla Pharma com ganho e troca das tricoins (pontos Triciclo) por benef\u00edcios e mais uma promo\u00e7\u00e3o da","og:url":"https:\/\/triciclo.eco.br\/en\/novas-recicla-pharmas-sao-instaladas-na-rede-de-farmacias-drogaria-sao-paulo\/","og:image":"https:\/\/triciclo.eco.br\/wp-content\/uploads\/2023\/08\/triciclo-logo-1.png","og:image:secure_url":"https:\/\/triciclo.eco.br\/wp-content\/uploads\/2023\/08\/triciclo-logo-1.png","og:image:width":200,"og:image:height":200,"article:published_time":"2021-09-15T18:15:47+00:00","article:modified_time":"2024-10-25T16:52:09+00:00","article:publisher":"https:\/\/www.facebook.com\/ambipar.triciclo","twitter:card":"summary_large_image","twitter:site":"@AmbiparTriciclo","twitter:title":"Novas Recicla Pharmas s\u00e3o instaladas na rede de farm\u00e1cias Drogaria S\u00e3o Paulo - Ambipar Triciclo","twitter:description":"Novas Recicla Pharmas s\u00e3o instaladas na rede de farm\u00e1cias Drogaria S\u00e3o Paulo Em conjunto com a L\u2019Oreal, Triciclo oferece descarte correto para res\u00edduos de classe farmac\u00eautica Medicamentos vencidos, em desuso e suas embalagens poder\u00e3o ser depositados na Recicla Pharma com ganho e troca das tricoins (pontos Triciclo) por benef\u00edcios e mais uma promo\u00e7\u00e3o da","twitter:creator":"@AmbiparTriciclo","twitter:image":"https:\/\/triciclo.eco.br\/wp-content\/uploads\/2023\/08\/Triciclo.jpg"},"aioseo_meta_data":{"post_id":"227786","title":null,"description":null,"keywords":null,"keyphrases":{"focus":{"keyphrase":"","score":0,"analysis":{"keyphraseInTitle":{"score":0,"maxScore":9,"error":1}}},"additional":[]},"primary_term":null,"canonical_url":null,"og_title":null,"og_description":null,"og_object_type":"default","og_image_type":"default","og_image_url":null,"og_image_width":null,"og_image_height":null,"og_image_custom_url":null,"og_image_custom_fields":null,"og_video":"","og_custom_url":null,"og_article_section":null,"og_article_tags":null,"twitter_use_og":false,"twitter_card":"default","twitter_image_type":"default","twitter_image_url":null,"twitter_image_custom_url":null,"twitter_image_custom_fields":null,"twitter_title":null,"twitter_description":null,"schema":{"blockGraphs":[],"customGraphs":[],"default":{"data":{"Article":[],"Course":[],"Dataset":[],"FAQPage":[],"Movie":[],"Person":[],"Product":[],"ProductReview":[],"Car":[],"Recipe":[],"Service":[],"SoftwareApplication":[],"WebPage":[]},"graphName":"BlogPosting","isEnabled":true},"graphs":[]},"schema_type":"default","schema_type_options":null,"pillar_content":false,"robots_default":true,"robots_noindex":false,"robots_noarchive":false,"robots_nosnippet":false,"robots_nofollow":false,"robots_noimageindex":false,"robots_noodp":false,"robots_notranslate":false,"robots_max_snippet":"-1","robots_max_videopreview":"-1","robots_max_imagepreview":"large","priority":null,"frequency":"default","local_seo":null,"breadcrumb_settings":null,"limit_modified_date":false,"ai":null,"created":"2023-08-29 18:09:33","updated":"2025-08-01 16:06:20","focus_keyword":null,"additional_keywords":null,"truseo_locale":null,"seo_analyzer_scan_date":null},"aioseo_breadcrumb":"<div class=\"aioseo-breadcrumbs\"><span class=\"aioseo-breadcrumb\">\n\t\t\t<a href=\"https:\/\/triciclo.eco.br\/en\" title=\"In\u00edcio\">In\u00edcio<\/a>\n\t\t<\/span><span class=\"aioseo-breadcrumb-separator\">&raquo;<\/span><span class=\"aioseo-breadcrumb\">\n\t\t\t<a href=\"https:\/\/triciclo.eco.br\/en\/category\/blog\/\" title=\"Blog\">Blog<\/a>\n\t\t<\/span><span class=\"aioseo-breadcrumb-separator\">&raquo;<\/span><span class=\"aioseo-breadcrumb\">\n\t\t\tNovas Recicla Pharmas s\u00e3o instaladas na rede de farm\u00e1cias Drogaria S\u00e3o Paulo\n\t\t<\/span><\/div>","aioseo_breadcrumb_json":[{"label":"In\u00edcio","link":"https:\/\/triciclo.eco.br\/en"},{"label":"Blog","link":"https:\/\/triciclo.eco.br\/en\/category\/blog\/"},{"label":"Novas Recicla Pharmas s\u00e3o instaladas na rede de farm\u00e1cias Drogaria S\u00e3o Paulo","link":"https:\/\/triciclo.eco.br\/en\/novas-recicla-pharmas-sao-instaladas-na-rede-de-farmacias-drogaria-sao-paulo\/"}],"jetpack_sharing_enabled":true,"jetpack_featured_media_url":"https:\/\/triciclo.eco.br\/wp-content\/uploads\/2021\/09\/Case-RP-LOreal-1.jpg","_links":{"self":[{"href":"https:\/\/triciclo.eco.br\/en\/wp-json\/wp\/v2\/posts\/227786","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/triciclo.eco.br\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/triciclo.eco.br\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/triciclo.eco.br\/en\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/triciclo.eco.br\/en\/wp-json\/wp\/v2\/comments?post=227786"}],"version-history":[{"count":7,"href":"https:\/\/triciclo.eco.br\/en\/wp-json\/wp\/v2\/posts\/227786\/revisions"}],"predecessor-version":[{"id":232246,"href":"https:\/\/triciclo.eco.br\/en\/wp-json\/wp\/v2\/posts\/227786\/revisions\/232246"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/triciclo.eco.br\/en\/wp-json\/wp\/v2\/media\/227822"}],"wp:attachment":[{"href":"https:\/\/triciclo.eco.br\/en\/wp-json\/wp\/v2\/media?parent=227786"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/triciclo.eco.br\/en\/wp-json\/wp\/v2\/categories?post=227786"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/triciclo.eco.br\/en\/wp-json\/wp\/v2\/tags?post=227786"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}