{"id":230798,"date":"2023-05-29T18:08:00","date_gmt":"2023-05-29T21:08:00","guid":{"rendered":"https:\/\/triciclo.eco.br\/?p=230798"},"modified":"2023-05-29T18:11:05","modified_gmt":"2023-05-29T21:11:05","slug":"leroy-merlin-firma-parceria-com-ambipar-triciclo-em-projeto-para-o-descarte-de-materiais-reciclaveis","status":"publish","type":"post","link":"https:\/\/triciclo.eco.br\/en\/leroy-merlin-firma-parceria-com-ambipar-triciclo-em-projeto-para-o-descarte-de-materiais-reciclaveis\/","title":{"rendered":"Leroy Merlin firma parceria com Ambipar Triciclo em projeto para o descarte de materiais recicl\u00e1veis"},"content":{"rendered":"<p>[et_pb_section fb_built=&#8221;1&#8243; _builder_version=&#8221;4.16&#8243; global_colors_info=&#8221;{}&#8221;][et_pb_row _builder_version=&#8221;4.17.3&#8243; background_size=&#8221;initial&#8221; background_position=&#8221;top_left&#8221; background_repeat=&#8221;repeat&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_column type=&#8221;4_4&#8243; _builder_version=&#8221;4.16&#8243; custom_padding=&#8221;|||&#8221; global_colors_info=&#8221;{}&#8221; custom_padding__hover=&#8221;|||&#8221;][et_pb_text _builder_version=&#8221;4.20.2&#8243; _module_preset=&#8221;default&#8221; text_font=&#8221;Montserrat|700|on||||||&#8221; text_font_size=&#8221;18px&#8221; global_colors_info=&#8221;{}&#8221;]<\/p>\n<p><span>Ecopontos foram implementados em seis unidades da varejista, e o descarte correto resulta na troca de pontos por benef\u00edcios<\/span><\/p>\n<p>[\/et_pb_text][et_pb_text _builder_version=&#8221;4.20.2&#8243; background_size=&#8221;initial&#8221; background_position=&#8221;top_left&#8221; background_repeat=&#8221;repeat&#8221; global_colors_info=&#8221;{}&#8221;]<\/p>\n<p>S\u00e3o Paulo, 25 de maio de 2023 \u2013 Como uma das formas de materializar a responsabilidade firmada em esferas sociais, ambientais e econ\u00f4micas, a LEROY MERLIN \u2013 uma das maiores redes de varejo do Brasil, focada em solu\u00e7\u00f5es completas para o lar \u2013 inicia uma parceria com a Ambipar Group, multinacional brasileira, pioneira em solu\u00e7\u00f5es em gest\u00e3o ambiental, por meio da Ambipar Triciclo, refer\u00eancia em solu\u00e7\u00f5es sustent\u00e1veis, para oferecer \u00e0 popula\u00e7\u00e3o espa\u00e7os destinados \u00e0 coleta seletiva de materiais recicl\u00e1veis.<\/p>\n<p>O projeto consiste na instala\u00e7\u00e3o de ecopontos para o recebimento de itens recicl\u00e1veis em seis unidades da companhia varejista, em Fortaleza (CE), Curitiba Sul (PR), Guarulhos (SP), Tiet\u00ea (SP), Interlagos (SP) e Morumbi (SP). Nos cont\u00eaineres, chamados de Deixaki, os consumidores podem descartar grandes volumes e diferentes tipologias de materiais p\u00f3s-consumo, como papel, papel\u00e3o, pl\u00e1stico, vidro, latas de alum\u00ednio\/a\u00e7o, eletroeletr\u00f4nicos e sucatas met\u00e1licas. Todo o material coletado pelos ecopontos \u00e9 enviado \u00e0 Ambipar Group para reaproveitamento e reciclagem, gerando mat\u00e9ria-prima, fonte de renda e emprego. Cada embalagem vale a moeda digital chamada de \u201ctricoins\u201d no Programa Triciclo de Fidelidade, e pode ser trocada por diversos benef\u00edcios, desde cr\u00e9ditos no Bilhete \u00danico \u2013 cart\u00e3o que d\u00e1 acesso ao transporte p\u00fablico na cidade de S\u00e3o Paulo \u2013, por exemplo, at\u00e9 recargas de celular e saldo positivo em alguns bancos digitais, como Mercado Pago e PagBank PagSeguro. Para ter acesso, \u00e9 necess\u00e1rio se cadastrar gratuitamente pelo aplicativo ou pelo site da Ambipar Triciclo.<\/p>\n<p>[\/et_pb_text][et_pb_text _builder_version=&#8221;4.20.2&#8243; background_size=&#8221;initial&#8221; background_position=&#8221;top_left&#8221; background_repeat=&#8221;repeat&#8221; global_colors_info=&#8221;{}&#8221;]<\/p>\n<p><span>Na vis\u00e3o de Mauro Filgueiras, gerente de Desenvolvimento Respons\u00e1vel da LEROY MERLIN, essa iniciativa dialoga com os pilares fortificados pela marca e contribui com a sociedade como um todo.<\/span><\/p>\n<p>[\/et_pb_text][et_pb_testimonial author=&#8221;Mauro Filgueiras&#8221; job_title=&#8221;Gerente de Desenvolvimento Respons\u00e1vel&#8221; company_name=&#8221;Leroy Merlin&#8221; quote_icon_color=&#8221;#c1d22a&#8221; quote_icon_background_color=&#8221;#FFFFFF&#8221; font_icon=&#8221;&#xe06a;||divi||400&#8243; use_icon_font_size=&#8221;on&#8221; icon_font_size=&#8221;45px&#8221; _builder_version=&#8221;4.20.2&#8243; _module_preset=&#8221;default&#8221; body_font_size=&#8221;17px&#8221; body_line_height=&#8221;1.3em&#8221; author_font=&#8221;|800|||||||&#8221; author_text_align=&#8221;center&#8221; author_font_size=&#8221;16px&#8221; author_line_height=&#8221;1em&#8221; company_font=&#8221;|600|||||||&#8221; text_orientation=&#8221;center&#8221; locked=&#8221;off&#8221; global_colors_info=&#8221;{}&#8221;]<\/p>\n<p><strong>A sustentabilidade faz parte do DNA da Leroy Merlin, ent\u00e3o atuamos em diferentes frentes, seja na concep\u00e7\u00e3o e desenvolvimento de produtos positivos, em propostas de economia circular e tamb\u00e9m na gest\u00e3o de res\u00edduos. Trata-se de uma pauta emergente, por isso precisamos disponibilizar solu\u00e7\u00f5es eficazes e conscientizar as pessoas<\/strong><\/p>\n<p>[\/et_pb_testimonial][et_pb_text _builder_version=&#8221;4.20.2&#8243; background_size=&#8221;initial&#8221; background_position=&#8221;top_left&#8221; background_repeat=&#8221;repeat&#8221; global_colors_info=&#8221;{}&#8221;]<\/p>\n<p><span>Para a Ambipar e seus neg\u00f3cios, regenerar faz parte de seu prop\u00f3sito, cujos princ\u00edpios da economia circular servem como pilares: a elimina\u00e7\u00e3o de res\u00edduos e polui\u00e7\u00e3o; a manuten\u00e7\u00e3o de produtos e materiais em uso e a regenera\u00e7\u00e3o dos sistemas naturais.<\/span><\/p>\n<p>[\/et_pb_text][et_pb_testimonial author=&#8221;Felipe Cury&#8221; job_title=&#8221;CEO&#8221; company_name=&#8221;Ambipar Triciclo&#8221; quote_icon_color=&#8221;#c1d22a&#8221; quote_icon_background_color=&#8221;#FFFFFF&#8221; font_icon=&#8221;&#xe06a;||divi||400&#8243; use_icon_font_size=&#8221;on&#8221; icon_font_size=&#8221;45px&#8221; _builder_version=&#8221;4.20.2&#8243; _module_preset=&#8221;default&#8221; body_font_size=&#8221;17px&#8221; body_line_height=&#8221;1.3em&#8221; author_font=&#8221;|800|||||||&#8221; author_text_align=&#8221;center&#8221; author_font_size=&#8221;16px&#8221; author_line_height=&#8221;1em&#8221; company_font=&#8221;|600|||||||&#8221; text_orientation=&#8221;center&#8221; locked=&#8221;off&#8221; global_colors_info=&#8221;{}&#8221;]<\/p>\n<p><strong>Com essa iniciativa, a Ambipar Triciclo trabalha para o desenvolvimento de equipamentos que servem tamb\u00e9m para educar a popula\u00e7\u00e3o. \u00c9 s\u00f3 fazer o descarte correto em um dos tr\u00eas equipamentos da Triciclo \u2013 o Deixaki, a Retorna Machine e a Recicla Pharma \u2013 gerando oportunidade para o consumidor final obter recursos, al\u00e9m de fazer a sua parte no descarte de materiais.<\/strong><\/p>\n<p>[\/et_pb_testimonial][et_pb_text _builder_version=&#8221;4.20.2&#8243; background_size=&#8221;initial&#8221; background_position=&#8221;top_left&#8221; background_repeat=&#8221;repeat&#8221; global_colors_info=&#8221;{}&#8221;]<\/p>\n<p><span>Para mais informa\u00e7\u00f5es acesse: <a href=\"https:\/\/triciclo.eco.br\/\">https:\/\/triciclo.eco.br\/<\/a><\/span><\/p>\n<p>[\/et_pb_text][et_pb_divider color=&#8221;#cccccc&#8221; divider_position=&#8221;center&#8221; _builder_version=&#8221;4.20.2&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221;][\/et_pb_divider][et_pb_text _builder_version=&#8221;4.20.2&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221;]<\/p>\n<p><strong>Sobre a Leroy Merlin<\/strong><\/p>\n<p>H\u00e1 24 anos no Brasil, a Leroy Merlin \u00e9 reconhecida como uma das mais importantes redes de varejo, focada em solu\u00e7\u00f5es completas para o lar. A companhia tem como objetivo proporcionar as melhores experi\u00eancias para os seus Clientes e, por esse motivo, os coloca no centro das tomadas de decis\u00f5es.<\/p>\n<p>Com uma estrat\u00e9gia omnicanal, atua em 45 Lojas f\u00edsicas em grandes formatos, duas unidades no conceito express e nas plataformas digitais, como e-commerce, televendas, WhatsApp e aplicativo.<\/p>\n<p>A empresa oferta um milh\u00e3o de itens, divididos em 15 se\u00e7\u00f5es: materiais de constru\u00e7\u00e3o, madeiras, el\u00e9trica, ferramentas, cer\u00e2mica, sanit\u00e1rios, encanamentos, jardim, ferragens, organiza\u00e7\u00e3o, pintura, decora\u00e7\u00e3o, pisos laminados &amp; vin\u00edlicos, ilumina\u00e7\u00e3o e cozinhas. Al\u00e9m disso, possui marcas exclusivas com o objetivo de trazer sempre os melhores produtos do mercado.<\/p>\n<p>A fim de possibilitar viv\u00eancias \u00fanicas, a Leroy Merlin entrega inspira\u00e7\u00e3o por meio de espa\u00e7os ambientados, oferece o Programa de Fidelidade Leroy Merlin Com Voc\u00ea que traz vantagens exclusivas para os membros participantes e o Leroy Merlin Instala que conta com mais de 130 servi\u00e7os dispon\u00edveis, uma rede de prestadores qualificados e a garantia da marca. Ainda podem ser encontrados nas unidades f\u00edsicas em grandes formatos: estacionamento amplo, Cart\u00e3o Presente, corte de madeiras, F\u00e1brica de Cores, drive-thru, sistema de lockers, Clique e Retire, al\u00e9m do Celebre!, cart\u00e3o que permite o parcelamento em at\u00e9 10 vezes sem juros.<\/p>\n<p>Com a\u00e7\u00f5es voltadas ao desenvolvimento das pessoas, a companhia disponibiliza a Universidade Corporativa, plataforma digital que concentra conte\u00fados relevantes e complementares \u00e0s miss\u00f5es dos mais de 10 mil Colaboradores. A Leroy Merlin tamb\u00e9m tem investido, cada vez mais, na \u00e1rea de Tecnologia &amp; Inova\u00e7\u00e3o, focando em melhorias cont\u00ednuas para os Clientes e Colaboradores.<\/p>\n<p>Em termos de premia\u00e7\u00f5es e certifica\u00e7\u00f5es, a companhia ocupa a 6.\u00aa posi\u00e7\u00e3o no ranking da GPTW Varejo, na categoria Super Grandes, que elenca as melhores empresas do segmento para trabalhar no Brasil e tamb\u00e9m foi certificada, em 2023, pelo Top Employers que consolida a companhia como uma das melhores empregadoras do pa\u00eds. Ainda, todas as Lojas f\u00edsicas de grande porte possuem a certifica\u00e7\u00e3o AQUA (Alta Qualidade Ambiental), voltada para a gest\u00e3o e uso sustent\u00e1vel dos edif\u00edcios.<\/p>\n<p>A marca \u00e9 parte integrante do ADEO, terceira maior pot\u00eancia do setor de materiais de constru\u00e7\u00e3o no mundo, e est\u00e1 presente em 13 estados brasileiros. Tem como pilar central a estrat\u00e9gia global We Make It Positive que transforma o neg\u00f3cio com 24 compromissos voltados \u00e0 sustentabilidade, inova\u00e7\u00e3o, gest\u00e3o da cadeia de valor e fomento ao desenvolvimento local. Confira mais informa\u00e7\u00f5es acerca das iniciativas aqui!<\/p>\n<p>[\/et_pb_text][et_pb_text _builder_version=&#8221;4.20.2&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221;]<\/p>\n<p><strong>Sobre a Ambipar Triciclo <\/strong><\/p>\n<p>A Ambipar Triciclo atua no mercado desde 2016, com a miss\u00e3o de criar e operar solu\u00e7\u00f5es para o desenvolvimento sustent\u00e1vel atrav\u00e9s da monetiza\u00e7\u00e3o do sistema de log\u00edstica reversa, fideliza\u00e7\u00e3o de clientes e um avan\u00e7ado sistema de marketing. Teve seu controle societ\u00e1rio adquirido pelo Grupo Ambipar em 2021 e \u00e9 a operadora dos Projetos Retorna Machine, Recicla Pharma e Deixaki, todos vinculados ao Programa de Fidelidade Triciclo. Nesse programa, as embalagens coletadas valem tricoins, que podem ser trocados por benef\u00edcios, como b\u00f4nus de energia el\u00e9trica, recarga de vale transporte, desconto em livraria, cr\u00e9dito em telefonia, cr\u00e9dito em conta digital e muito mais. Todo o material coletado \u00e9 tratado pela pr\u00f3pria Ambipar Triciclo para envio \u00e0s cooperativas e empresas recicladoras. Em 6 anos de opera\u00e7\u00e3o, j\u00e1 coletou mais de 25 milh\u00f5es de embalagens p\u00f3s-consumo, gerando fonte de renda, mat\u00e9ria-prima e trabalho. Sobre a Ambipar Com escrit\u00f3rio administrativo em S\u00e3o Paulo e matriz em Nova Odessa \u2013 SP, a Ambipar \u00e9 uma multinacional brasileira, com presen\u00e7a em 39 pa\u00edses ao todo. Formada pela Ambipar Environment e Ambipar Response, segmentos de refer\u00eancia no mercado de gest\u00e3o ambiental, tem em seu DNA o comprometimento com as quest\u00f5es sustent\u00e1veis, trabalhando os Pilares ESG dentro de seus neg\u00f3cios e apoiando seus clientes.<\/p>\n<p>[\/et_pb_text][\/et_pb_column][\/et_pb_row][et_pb_row _builder_version=&#8221;4.20.2&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_column type=&#8221;4_4&#8243; _builder_version=&#8221;4.20.2&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221;][difl_imagecarousel use_lightbox=&#8221;on&#8221; arrow_prev_icon_use_icon=&#8221;on&#8221; arrow_prev_icon_font_icon=&#8221;&#x3c;||divi||400&#8243; arrow_next_icon_use_icon=&#8221;on&#8221; arrow_next_icon_font_icon=&#8221;&#x3d;||divi||400&#8243; arrow_color=&#8221;#BED022&#8243; arrow_background=&#8221;#FFFFFF&#8221; vertical_align=&#8221;center&#8221; image_scale=&#8221;on&#8221; content_hover=&#8221;on&#8221; anim_direction=&#8221;center&#8221; admin_label=&#8221;Leroy Merlin&#8221; _builder_version=&#8221;4.20.2&#8243; _module_preset=&#8221;default&#8221; caption_font=&#8221;Montserrat|700|||||||&#8221; caption_text_align=&#8221;center&#8221; caption_text_color=&#8221;#FFFFFF&#8221; locked=&#8221;off&#8221; global_colors_info=&#8221;{}&#8221; ic_overlay_background_bgcolor__hover_enabled=&#8221;on|hover&#8221; ic_overlay_background_bgcolor__hover=&#8221;rgba(0,0,0,0.31)&#8221;][difl_imagecarouselitem admin_label=&#8221;Leroy Merlin &#8211; Interlagos&#8221; image=&#8221;https:\/\/triciclo.eco.br\/wp-content\/uploads\/2023\/05\/Leroy-Merlin-Interlagos-case.jpg&#8221; alt_text=&#8221;Leroy Merlin &#8211; Interlagos&#8221; caption=&#8221;Leroy Merlin &#8211; Interlagos&#8221; ic_button_button_url_new_window=&#8221;1&#8243; _builder_version=&#8221;4.20.2&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221;][\/difl_imagecarouselitem][difl_imagecarouselitem admin_label=&#8221;Leroy Merlin &#8211; Tiet\u00ea&#8221; image=&#8221;https:\/\/triciclo.eco.br\/wp-content\/uploads\/2023\/05\/Leroy-Merlin-Tiete.jpg&#8221; alt_text=&#8221;Leroy Merlin &#8211; Tiet\u00ea&#8221; caption=&#8221;Leroy Merlin &#8211; Tiet\u00ea&#8221; ic_button_button_url_new_window=&#8221;1&#8243; _builder_version=&#8221;4.20.2&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221;][\/difl_imagecarouselitem][difl_imagecarouselitem admin_label=&#8221;Leroy Merlin &#8211; Morumbi&#8221; image=&#8221;https:\/\/triciclo.eco.br\/wp-content\/uploads\/2023\/05\/LeroyMerlin-Morumbi-01.jpg&#8221; alt_text=&#8221;Leroy Merlin &#8211; Morumbi&#8221; caption=&#8221;Leroy Merlin &#8211; Morumbi&#8221; ic_button_button_url_new_window=&#8221;1&#8243; _builder_version=&#8221;4.20.2&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221;][\/difl_imagecarouselitem][difl_imagecarouselitem admin_label=&#8221;Leroy Merlin &#8211; Curitiba&#8221; image=&#8221;https:\/\/triciclo.eco.br\/wp-content\/uploads\/2023\/05\/Leroy-Merlin-Curitiba-case.jpg&#8221; alt_text=&#8221;Leroy Merlin &#8211; Curitiba&#8221; caption=&#8221;Leroy Merlin &#8211; Curitiba&#8221; ic_button_button_url_new_window=&#8221;1&#8243; _builder_version=&#8221;4.20.2&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221;][\/difl_imagecarouselitem][difl_imagecarouselitem admin_label=&#8221;Leroy Merlin &#8211; Fortaleza&#8221; image=&#8221;https:\/\/triciclo.eco.br\/wp-content\/uploads\/2023\/05\/IMG-20230526-WA0058-gigapixel-standard-scale-2_00x.jpg&#8221; alt_text=&#8221;Leroy Merlin &#8211; Fortaleza&#8221; caption=&#8221;Leroy Merlin &#8211; Fortaleza&#8221; ic_button_button_url_new_window=&#8221;1&#8243; _builder_version=&#8221;4.20.2&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221;][\/difl_imagecarouselitem][\/difl_imagecarousel][\/et_pb_column][\/et_pb_row][\/et_pb_section]<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Ecopontos foram implementados em seis unidades da varejista, e o descarte correto resulta na troca de pontos por benef\u00edciosS\u00e3o Paulo, 25 de maio de 2023 \u2013 Como uma das formas de materializar a responsabilidade firmada em esferas sociais, ambientais e econ\u00f4micas, a LEROY MERLIN \u2013 uma das maiores redes de varejo do Brasil, focada em [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":230791,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_et_pb_use_builder":"on","_et_pb_old_content":"<p>\"S\u00f3 um coletivo organizado de institui\u00e7\u00f5es p\u00fablicas e privadas, com a colabora\u00e7\u00e3o de pessoas atuantes, \u00e9 capaz de criar uma onda de restaura\u00e7\u00e3o em larga escala no pa\u00eds.\"<\/p><p>O Restaura Brasil \u00e9 uma campanha da The Nature Conservancy (TNC) para mobilizar pessoas e empresas em um movimento coletivo para restaurar 1 bilh\u00e3o de \u00e1rvores no pa\u00eds at\u00e9 2030 e contribuir para que o governo brasileiro alcance sua meta de mitiga\u00e7\u00e3o \u00e0s mudan\u00e7as clim\u00e1ticas no Acordo de Paris.<\/p><p>A restaura\u00e7\u00e3o florestal \u00e9 uma das maiores oportunidade para minimizar as mudan\u00e7as clim\u00e1ticas. Temos que limitar o aumento da temperatura terrestre at\u00e9 1,5\u00baC.<\/p><p>POR QUE RESTAURAR ?<br \/>A vegeta\u00e7\u00e3o natural tem um papel essencial no ciclo da \u00e1gua e na estabiliza\u00e7\u00e3o clim\u00e1tica, al\u00e9m de fornecer alimento, mat\u00e9ria-prima para diversos setores e um ambiente rico em plantas e animais. Para alcan\u00e7ar os compromissos do pa\u00eds no Acordo de Paris \u00e9 preciso acelerar a restaura\u00e7\u00e3o florestal no Brasil, com o engajamento de toda a sociedade.<\/p><p>A The Nature Conservancy (TNC) ajudou na formula\u00e7\u00e3o da pol\u00edtica e do plano nacional de restaura\u00e7\u00e3o da vegeta\u00e7\u00e3o nativa (PLANAVEG) e foi eleita uma das quatro institui\u00e7\u00f5es da sociedade civil a compor o Comit\u00ea Nacional para Recupera\u00e7\u00e3o da Vegeta\u00e7\u00e3o Nativa.<\/p>","_et_gb_content_width":"","_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_memberships_contains_paid_content":false,"footnotes":""},"categories":[8],"tags":[189,197,203,204],"class_list":["post-230798","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-blog","tag-ambipar","tag-ambipar-triciclo","tag-deixaki","tag-leroy-merlin"],"aioseo_notices":[],"aioseo_head":"\n\t\t<!-- All in One SEO 5.0.0.1 - aioseo.com -->\n\t<meta name=\"description\" content=\"Ecopontos foram implementados em seis unidades da varejista, e o descarte correto resulta na troca de pontos por benef\u00edcios S\u00e3o Paulo, 25 de maio de 2023 \u2013 Como uma das formas de materializar a responsabilidade firmada em esferas sociais, ambientais e econ\u00f4micas, a LEROY MERLIN \u2013 uma das maiores redes de varejo do Brasil, focada\" \/>\n\t<meta name=\"robots\" content=\"max-image-preview:large\" \/>\n\t<meta name=\"author\" content=\"Triciclo\"\/>\n\t<link rel=\"canonical\" href=\"https:\/\/triciclo.eco.br\/en\/leroy-merlin-firma-parceria-com-ambipar-triciclo-em-projeto-para-o-descarte-de-materiais-reciclaveis\/\" \/>\n\t<meta name=\"generator\" content=\"All in One SEO (AIOSEO) 5.0.0.1\" \/>\n\t\t<meta property=\"og:locale\" content=\"en_US\" \/>\n\t\t<meta property=\"og:site_name\" content=\"Ambipar Triciclo - Solu\u00e7\u00f5es Sustent\u00e1veis\" \/>\n\t\t<meta property=\"og:type\" content=\"article\" \/>\n\t\t<meta property=\"og:title\" content=\"Leroy Merlin firma parceria com Ambipar Triciclo em projeto para o descarte de materiais recicl\u00e1veis - Ambipar Triciclo\" \/>\n\t\t<meta property=\"og:description\" content=\"Ecopontos foram implementados em seis unidades da varejista, e o descarte correto resulta na troca de pontos por benef\u00edcios S\u00e3o Paulo, 25 de maio de 2023 \u2013 Como uma das formas de materializar a responsabilidade firmada em esferas sociais, ambientais e econ\u00f4micas, a LEROY MERLIN \u2013 uma das maiores redes de varejo do Brasil, focada\" \/>\n\t\t<meta property=\"og:url\" content=\"https:\/\/triciclo.eco.br\/en\/leroy-merlin-firma-parceria-com-ambipar-triciclo-em-projeto-para-o-descarte-de-materiais-reciclaveis\/\" \/>\n\t\t<meta property=\"og:image\" content=\"https:\/\/triciclo.eco.br\/wp-content\/uploads\/2023\/08\/triciclo-logo-1.png\" \/>\n\t\t<meta property=\"og:image:secure_url\" content=\"https:\/\/triciclo.eco.br\/wp-content\/uploads\/2023\/08\/triciclo-logo-1.png\" \/>\n\t\t<meta property=\"og:image:width\" content=\"200\" \/>\n\t\t<meta property=\"og:image:height\" content=\"200\" \/>\n\t\t<meta property=\"article:published_time\" content=\"2023-05-29T21:08:00+00:00\" \/>\n\t\t<meta property=\"article:modified_time\" content=\"2023-05-29T21:11:05+00:00\" \/>\n\t\t<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/ambipar.triciclo\" \/>\n\t\t<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n\t\t<meta name=\"twitter:site\" content=\"@AmbiparTriciclo\" \/>\n\t\t<meta name=\"twitter:title\" content=\"Leroy Merlin firma parceria com Ambipar Triciclo em projeto para o descarte de materiais recicl\u00e1veis - Ambipar Triciclo\" \/>\n\t\t<meta name=\"twitter:description\" content=\"Ecopontos foram implementados em seis unidades da varejista, e o descarte correto resulta na troca de pontos por benef\u00edcios S\u00e3o Paulo, 25 de maio de 2023 \u2013 Como uma das formas de materializar a responsabilidade firmada em esferas sociais, ambientais e econ\u00f4micas, a LEROY MERLIN \u2013 uma das maiores redes de varejo do Brasil, focada\" \/>\n\t\t<meta name=\"twitter:creator\" content=\"@AmbiparTriciclo\" \/>\n\t\t<meta name=\"twitter:image\" content=\"https:\/\/triciclo.eco.br\/wp-content\/uploads\/2023\/08\/Triciclo.jpg\" \/>\n\t\t<script type=\"application\/ld+json\" class=\"aioseo-schema\">\n\t\t\t{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"BlogPosting\",\"@id\":\"https:\\\/\\\/triciclo.eco.br\\\/en\\\/leroy-merlin-firma-parceria-com-ambipar-triciclo-em-projeto-para-o-descarte-de-materiais-reciclaveis\\\/#blogposting\",\"name\":\"Leroy Merlin firma parceria com Ambipar Triciclo em projeto para o descarte de materiais recicl\\u00e1veis - Ambipar Triciclo\",\"headline\":\"Leroy Merlin firma parceria com Ambipar Triciclo em projeto para o descarte de materiais recicl\\u00e1veis\",\"author\":{\"@id\":\"https:\\\/\\\/triciclo.eco.br\\\/en\\\/author\\\/triciclo\\\/#author\"},\"publisher\":{\"@id\":\"https:\\\/\\\/triciclo.eco.br\\\/en\\\/#organization\"},\"image\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/triciclo.eco.br\\\/wp-content\\\/uploads\\\/2023\\\/05\\\/IMG-20230425-WA0030-gigapixel-hq-width-2000px.jpg\",\"width\":2000,\"height\":1500,\"caption\":\"Deixaki - Leroy Merlin - case Ambipar Triciclo\"},\"datePublished\":\"2023-05-29T18:08:00-03:00\",\"dateModified\":\"2023-05-29T18:11:05-03:00\",\"inLanguage\":\"en-US\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/triciclo.eco.br\\\/en\\\/leroy-merlin-firma-parceria-com-ambipar-triciclo-em-projeto-para-o-descarte-de-materiais-reciclaveis\\\/#webpage\"},\"isPartOf\":{\"@id\":\"https:\\\/\\\/triciclo.eco.br\\\/en\\\/leroy-merlin-firma-parceria-com-ambipar-triciclo-em-projeto-para-o-descarte-de-materiais-reciclaveis\\\/#webpage\"},\"articleSection\":\"Blog, Ambipar, Ambipar Triciclo, Deixaki, Leroy Merlin\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/triciclo.eco.br\\\/en\\\/leroy-merlin-firma-parceria-com-ambipar-triciclo-em-projeto-para-o-descarte-de-materiais-reciclaveis\\\/#breadcrumblist\",\"itemListElement\":[{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/triciclo.eco.br\\\/en#listItem\",\"position\":1,\"name\":\"In\\u00edcio\",\"item\":\"https:\\\/\\\/triciclo.eco.br\\\/en\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/triciclo.eco.br\\\/en\\\/category\\\/blog\\\/#listItem\",\"name\":\"Blog\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/triciclo.eco.br\\\/en\\\/category\\\/blog\\\/#listItem\",\"position\":2,\"name\":\"Blog\",\"item\":\"https:\\\/\\\/triciclo.eco.br\\\/en\\\/category\\\/blog\\\/\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/triciclo.eco.br\\\/en\\\/leroy-merlin-firma-parceria-com-ambipar-triciclo-em-projeto-para-o-descarte-de-materiais-reciclaveis\\\/#listItem\",\"name\":\"Leroy Merlin firma parceria com Ambipar Triciclo em projeto para o descarte de materiais recicl\\u00e1veis\"},\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/triciclo.eco.br\\\/en#listItem\",\"name\":\"In\\u00edcio\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/triciclo.eco.br\\\/en\\\/leroy-merlin-firma-parceria-com-ambipar-triciclo-em-projeto-para-o-descarte-de-materiais-reciclaveis\\\/#listItem\",\"position\":3,\"name\":\"Leroy Merlin firma parceria com Ambipar Triciclo em projeto para o descarte de materiais recicl\\u00e1veis\",\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/triciclo.eco.br\\\/en\\\/category\\\/blog\\\/#listItem\",\"name\":\"Blog\"}}]},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/triciclo.eco.br\\\/en\\\/#organization\",\"name\":\"Ambipar Triciclo Solu\\u00e7\\u00f5es Sustent\\u00e1veis\",\"description\":\"Solu\\u00e7\\u00f5es Sustent\\u00e1veis\",\"url\":\"https:\\\/\\\/triciclo.eco.br\\\/en\\\/\",\"telephone\":\"+551134295050\",\"logo\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/triciclo.eco.br\\\/wp-content\\\/uploads\\\/2023\\\/08\\\/Triciclo.jpg\",\"@id\":\"https:\\\/\\\/triciclo.eco.br\\\/en\\\/leroy-merlin-firma-parceria-com-ambipar-triciclo-em-projeto-para-o-descarte-de-materiais-reciclaveis\\\/#organizationLogo\",\"width\":113,\"height\":113},\"image\":{\"@id\":\"https:\\\/\\\/triciclo.eco.br\\\/en\\\/leroy-merlin-firma-parceria-com-ambipar-triciclo-em-projeto-para-o-descarte-de-materiais-reciclaveis\\\/#organizationLogo\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/ambipar.triciclo\",\"https:\\\/\\\/twitter.com\\\/AmbiparTriciclo\",\"https:\\\/\\\/www.instagram.com\\\/triciclo_retornamachine\\\/\",\"https:\\\/\\\/www.youtube.com\\\/@TricicloSolucoesSustentaveis\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/triciclo-solues-sustentveis\\\/\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/triciclo.eco.br\\\/en\\\/author\\\/triciclo\\\/#author\",\"url\":\"https:\\\/\\\/triciclo.eco.br\\\/en\\\/author\\\/triciclo\\\/\",\"name\":\"Triciclo\",\"image\":{\"@type\":\"ImageObject\",\"@id\":\"https:\\\/\\\/triciclo.eco.br\\\/en\\\/leroy-merlin-firma-parceria-com-ambipar-triciclo-em-projeto-para-o-descarte-de-materiais-reciclaveis\\\/#authorImage\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/8031027e39acb0f958577a55663464ac1cd1ffb991a23bf69b3ffbe38b0ecfbf?s=96&d=mm&r=g\",\"width\":96,\"height\":96,\"caption\":\"Triciclo\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/triciclo.eco.br\\\/en\\\/leroy-merlin-firma-parceria-com-ambipar-triciclo-em-projeto-para-o-descarte-de-materiais-reciclaveis\\\/#webpage\",\"url\":\"https:\\\/\\\/triciclo.eco.br\\\/en\\\/leroy-merlin-firma-parceria-com-ambipar-triciclo-em-projeto-para-o-descarte-de-materiais-reciclaveis\\\/\",\"name\":\"Leroy Merlin firma parceria com Ambipar Triciclo em projeto para o descarte de materiais recicl\\u00e1veis - Ambipar Triciclo\",\"description\":\"Ecopontos foram implementados em seis unidades da varejista, e o descarte correto resulta na troca de pontos por benef\\u00edcios S\\u00e3o Paulo, 25 de maio de 2023 \\u2013 Como uma das formas de materializar a responsabilidade firmada em esferas sociais, ambientais e econ\\u00f4micas, a LEROY MERLIN \\u2013 uma das maiores redes de varejo do Brasil, focada\",\"inLanguage\":\"en-US\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/triciclo.eco.br\\\/en\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/triciclo.eco.br\\\/en\\\/leroy-merlin-firma-parceria-com-ambipar-triciclo-em-projeto-para-o-descarte-de-materiais-reciclaveis\\\/#breadcrumblist\"},\"author\":{\"@id\":\"https:\\\/\\\/triciclo.eco.br\\\/en\\\/author\\\/triciclo\\\/#author\"},\"creator\":{\"@id\":\"https:\\\/\\\/triciclo.eco.br\\\/en\\\/author\\\/triciclo\\\/#author\"},\"image\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/triciclo.eco.br\\\/wp-content\\\/uploads\\\/2023\\\/05\\\/IMG-20230425-WA0030-gigapixel-hq-width-2000px.jpg\",\"@id\":\"https:\\\/\\\/triciclo.eco.br\\\/en\\\/leroy-merlin-firma-parceria-com-ambipar-triciclo-em-projeto-para-o-descarte-de-materiais-reciclaveis\\\/#mainImage\",\"width\":2000,\"height\":1500,\"caption\":\"Deixaki - Leroy Merlin - case Ambipar Triciclo\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/triciclo.eco.br\\\/en\\\/leroy-merlin-firma-parceria-com-ambipar-triciclo-em-projeto-para-o-descarte-de-materiais-reciclaveis\\\/#mainImage\"},\"datePublished\":\"2023-05-29T18:08:00-03:00\",\"dateModified\":\"2023-05-29T18:11:05-03:00\"},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/triciclo.eco.br\\\/en\\\/#website\",\"url\":\"https:\\\/\\\/triciclo.eco.br\\\/en\\\/\",\"name\":\"Ambipar Triciclo\",\"alternateName\":\"Triciclo\",\"description\":\"Solu\\u00e7\\u00f5es Sustent\\u00e1veis\",\"inLanguage\":\"en-US\",\"publisher\":{\"@id\":\"https:\\\/\\\/triciclo.eco.br\\\/en\\\/#organization\"}}]}\n\t\t<\/script>\n\t\t<!-- All in One SEO -->\n\n","aioseo_head_json":{"title":"Leroy Merlin firma parceria com Ambipar Triciclo em projeto para o descarte de materiais recicl\u00e1veis - Ambipar Triciclo","description":"Ecopontos foram implementados em seis unidades da varejista, e o descarte correto resulta na troca de pontos por benef\u00edcios S\u00e3o Paulo, 25 de maio de 2023 \u2013 Como uma das formas de materializar a responsabilidade firmada em esferas sociais, ambientais e econ\u00f4micas, a LEROY MERLIN \u2013 uma das maiores redes de varejo do Brasil, focada","canonical_url":"https:\/\/triciclo.eco.br\/en\/leroy-merlin-firma-parceria-com-ambipar-triciclo-em-projeto-para-o-descarte-de-materiais-reciclaveis\/","robots":"max-image-preview:large","keywords":"","webmasterTools":{"miscellaneous":""},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"BlogPosting","@id":"https:\/\/triciclo.eco.br\/en\/leroy-merlin-firma-parceria-com-ambipar-triciclo-em-projeto-para-o-descarte-de-materiais-reciclaveis\/#blogposting","name":"Leroy Merlin firma parceria com Ambipar Triciclo em projeto para o descarte de materiais recicl\u00e1veis - Ambipar Triciclo","headline":"Leroy Merlin firma parceria com Ambipar Triciclo em projeto para o descarte de materiais recicl\u00e1veis","author":{"@id":"https:\/\/triciclo.eco.br\/en\/author\/triciclo\/#author"},"publisher":{"@id":"https:\/\/triciclo.eco.br\/en\/#organization"},"image":{"@type":"ImageObject","url":"https:\/\/triciclo.eco.br\/wp-content\/uploads\/2023\/05\/IMG-20230425-WA0030-gigapixel-hq-width-2000px.jpg","width":2000,"height":1500,"caption":"Deixaki - Leroy Merlin - case Ambipar Triciclo"},"datePublished":"2023-05-29T18:08:00-03:00","dateModified":"2023-05-29T18:11:05-03:00","inLanguage":"en-US","mainEntityOfPage":{"@id":"https:\/\/triciclo.eco.br\/en\/leroy-merlin-firma-parceria-com-ambipar-triciclo-em-projeto-para-o-descarte-de-materiais-reciclaveis\/#webpage"},"isPartOf":{"@id":"https:\/\/triciclo.eco.br\/en\/leroy-merlin-firma-parceria-com-ambipar-triciclo-em-projeto-para-o-descarte-de-materiais-reciclaveis\/#webpage"},"articleSection":"Blog, Ambipar, Ambipar Triciclo, Deixaki, Leroy Merlin"},{"@type":"BreadcrumbList","@id":"https:\/\/triciclo.eco.br\/en\/leroy-merlin-firma-parceria-com-ambipar-triciclo-em-projeto-para-o-descarte-de-materiais-reciclaveis\/#breadcrumblist","itemListElement":[{"@type":"ListItem","@id":"https:\/\/triciclo.eco.br\/en#listItem","position":1,"name":"In\u00edcio","item":"https:\/\/triciclo.eco.br\/en","nextItem":{"@type":"ListItem","@id":"https:\/\/triciclo.eco.br\/en\/category\/blog\/#listItem","name":"Blog"}},{"@type":"ListItem","@id":"https:\/\/triciclo.eco.br\/en\/category\/blog\/#listItem","position":2,"name":"Blog","item":"https:\/\/triciclo.eco.br\/en\/category\/blog\/","nextItem":{"@type":"ListItem","@id":"https:\/\/triciclo.eco.br\/en\/leroy-merlin-firma-parceria-com-ambipar-triciclo-em-projeto-para-o-descarte-de-materiais-reciclaveis\/#listItem","name":"Leroy Merlin firma parceria com Ambipar Triciclo em projeto para o descarte de materiais recicl\u00e1veis"},"previousItem":{"@type":"ListItem","@id":"https:\/\/triciclo.eco.br\/en#listItem","name":"In\u00edcio"}},{"@type":"ListItem","@id":"https:\/\/triciclo.eco.br\/en\/leroy-merlin-firma-parceria-com-ambipar-triciclo-em-projeto-para-o-descarte-de-materiais-reciclaveis\/#listItem","position":3,"name":"Leroy Merlin firma parceria com Ambipar Triciclo em projeto para o descarte de materiais recicl\u00e1veis","previousItem":{"@type":"ListItem","@id":"https:\/\/triciclo.eco.br\/en\/category\/blog\/#listItem","name":"Blog"}}]},{"@type":"Organization","@id":"https:\/\/triciclo.eco.br\/en\/#organization","name":"Ambipar Triciclo Solu\u00e7\u00f5es Sustent\u00e1veis","description":"Solu\u00e7\u00f5es Sustent\u00e1veis","url":"https:\/\/triciclo.eco.br\/en\/","telephone":"+551134295050","logo":{"@type":"ImageObject","url":"https:\/\/triciclo.eco.br\/wp-content\/uploads\/2023\/08\/Triciclo.jpg","@id":"https:\/\/triciclo.eco.br\/en\/leroy-merlin-firma-parceria-com-ambipar-triciclo-em-projeto-para-o-descarte-de-materiais-reciclaveis\/#organizationLogo","width":113,"height":113},"image":{"@id":"https:\/\/triciclo.eco.br\/en\/leroy-merlin-firma-parceria-com-ambipar-triciclo-em-projeto-para-o-descarte-de-materiais-reciclaveis\/#organizationLogo"},"sameAs":["https:\/\/www.facebook.com\/ambipar.triciclo","https:\/\/twitter.com\/AmbiparTriciclo","https:\/\/www.instagram.com\/triciclo_retornamachine\/","https:\/\/www.youtube.com\/@TricicloSolucoesSustentaveis","https:\/\/www.linkedin.com\/company\/triciclo-solues-sustentveis\/"]},{"@type":"Person","@id":"https:\/\/triciclo.eco.br\/en\/author\/triciclo\/#author","url":"https:\/\/triciclo.eco.br\/en\/author\/triciclo\/","name":"Triciclo","image":{"@type":"ImageObject","@id":"https:\/\/triciclo.eco.br\/en\/leroy-merlin-firma-parceria-com-ambipar-triciclo-em-projeto-para-o-descarte-de-materiais-reciclaveis\/#authorImage","url":"https:\/\/secure.gravatar.com\/avatar\/8031027e39acb0f958577a55663464ac1cd1ffb991a23bf69b3ffbe38b0ecfbf?s=96&d=mm&r=g","width":96,"height":96,"caption":"Triciclo"}},{"@type":"WebPage","@id":"https:\/\/triciclo.eco.br\/en\/leroy-merlin-firma-parceria-com-ambipar-triciclo-em-projeto-para-o-descarte-de-materiais-reciclaveis\/#webpage","url":"https:\/\/triciclo.eco.br\/en\/leroy-merlin-firma-parceria-com-ambipar-triciclo-em-projeto-para-o-descarte-de-materiais-reciclaveis\/","name":"Leroy Merlin firma parceria com Ambipar Triciclo em projeto para o descarte de materiais recicl\u00e1veis - Ambipar Triciclo","description":"Ecopontos foram implementados em seis unidades da varejista, e o descarte correto resulta na troca de pontos por benef\u00edcios S\u00e3o Paulo, 25 de maio de 2023 \u2013 Como uma das formas de materializar a responsabilidade firmada em esferas sociais, ambientais e econ\u00f4micas, a LEROY MERLIN \u2013 uma das maiores redes de varejo do Brasil, focada","inLanguage":"en-US","isPartOf":{"@id":"https:\/\/triciclo.eco.br\/en\/#website"},"breadcrumb":{"@id":"https:\/\/triciclo.eco.br\/en\/leroy-merlin-firma-parceria-com-ambipar-triciclo-em-projeto-para-o-descarte-de-materiais-reciclaveis\/#breadcrumblist"},"author":{"@id":"https:\/\/triciclo.eco.br\/en\/author\/triciclo\/#author"},"creator":{"@id":"https:\/\/triciclo.eco.br\/en\/author\/triciclo\/#author"},"image":{"@type":"ImageObject","url":"https:\/\/triciclo.eco.br\/wp-content\/uploads\/2023\/05\/IMG-20230425-WA0030-gigapixel-hq-width-2000px.jpg","@id":"https:\/\/triciclo.eco.br\/en\/leroy-merlin-firma-parceria-com-ambipar-triciclo-em-projeto-para-o-descarte-de-materiais-reciclaveis\/#mainImage","width":2000,"height":1500,"caption":"Deixaki - Leroy Merlin - case Ambipar Triciclo"},"primaryImageOfPage":{"@id":"https:\/\/triciclo.eco.br\/en\/leroy-merlin-firma-parceria-com-ambipar-triciclo-em-projeto-para-o-descarte-de-materiais-reciclaveis\/#mainImage"},"datePublished":"2023-05-29T18:08:00-03:00","dateModified":"2023-05-29T18:11:05-03:00"},{"@type":"WebSite","@id":"https:\/\/triciclo.eco.br\/en\/#website","url":"https:\/\/triciclo.eco.br\/en\/","name":"Ambipar Triciclo","alternateName":"Triciclo","description":"Solu\u00e7\u00f5es Sustent\u00e1veis","inLanguage":"en-US","publisher":{"@id":"https:\/\/triciclo.eco.br\/en\/#organization"}}]},"og:locale":"en_US","og:site_name":"Ambipar Triciclo - Solu\u00e7\u00f5es Sustent\u00e1veis","og:type":"article","og:title":"Leroy Merlin firma parceria com Ambipar Triciclo em projeto para o descarte de materiais recicl\u00e1veis - Ambipar Triciclo","og:description":"Ecopontos foram implementados em seis unidades da varejista, e o descarte correto resulta na troca de pontos por benef\u00edcios S\u00e3o Paulo, 25 de maio de 2023 \u2013 Como uma das formas de materializar a responsabilidade firmada em esferas sociais, ambientais e econ\u00f4micas, a LEROY MERLIN \u2013 uma das maiores redes de varejo do Brasil, focada","og:url":"https:\/\/triciclo.eco.br\/en\/leroy-merlin-firma-parceria-com-ambipar-triciclo-em-projeto-para-o-descarte-de-materiais-reciclaveis\/","og:image":"https:\/\/triciclo.eco.br\/wp-content\/uploads\/2023\/08\/triciclo-logo-1.png","og:image:secure_url":"https:\/\/triciclo.eco.br\/wp-content\/uploads\/2023\/08\/triciclo-logo-1.png","og:image:width":200,"og:image:height":200,"article:published_time":"2023-05-29T21:08:00+00:00","article:modified_time":"2023-05-29T21:11:05+00:00","article:publisher":"https:\/\/www.facebook.com\/ambipar.triciclo","twitter:card":"summary_large_image","twitter:site":"@AmbiparTriciclo","twitter:title":"Leroy Merlin firma parceria com Ambipar Triciclo em projeto para o descarte de materiais recicl\u00e1veis - Ambipar Triciclo","twitter:description":"Ecopontos foram implementados em seis unidades da varejista, e o descarte correto resulta na troca de pontos por benef\u00edcios S\u00e3o Paulo, 25 de maio de 2023 \u2013 Como uma das formas de materializar a responsabilidade firmada em esferas sociais, ambientais e econ\u00f4micas, a LEROY MERLIN \u2013 uma das maiores redes de varejo do Brasil, focada","twitter:creator":"@AmbiparTriciclo","twitter:image":"https:\/\/triciclo.eco.br\/wp-content\/uploads\/2023\/08\/Triciclo.jpg"},"aioseo_meta_data":{"post_id":"230798","title":null,"description":null,"keywords":null,"keyphrases":null,"primary_term":null,"canonical_url":null,"og_title":null,"og_description":null,"og_object_type":"default","og_image_type":"default","og_image_url":null,"og_image_width":null,"og_image_height":null,"og_image_custom_url":null,"og_image_custom_fields":null,"og_video":null,"og_custom_url":null,"og_article_section":null,"og_article_tags":null,"twitter_use_og":false,"twitter_card":"default","twitter_image_type":"default","twitter_image_url":null,"twitter_image_custom_url":null,"twitter_image_custom_fields":null,"twitter_title":null,"twitter_description":null,"schema":{"blockGraphs":[],"customGraphs":[],"default":{"data":{"Article":[],"Course":[],"Dataset":[],"FAQPage":[],"Movie":[],"Person":[],"Product":[],"ProductReview":[],"Car":[],"Recipe":[],"Service":[],"SoftwareApplication":[],"WebPage":[]},"graphName":"","isEnabled":true},"graphs":[]},"schema_type":"default","schema_type_options":null,"pillar_content":false,"robots_default":true,"robots_noindex":false,"robots_noarchive":false,"robots_nosnippet":false,"robots_nofollow":false,"robots_noimageindex":false,"robots_noodp":false,"robots_notranslate":false,"robots_max_snippet":null,"robots_max_videopreview":null,"robots_max_imagepreview":"large","priority":null,"frequency":null,"local_seo":null,"breadcrumb_settings":null,"limit_modified_date":false,"ai":null,"created":"2023-08-29 18:27:49","updated":"2025-08-01 16:11:16","focus_keyword":null,"additional_keywords":null,"truseo_locale":null,"seo_analyzer_scan_date":null},"aioseo_breadcrumb":"<div class=\"aioseo-breadcrumbs\"><span class=\"aioseo-breadcrumb\">\n\t\t\t<a href=\"https:\/\/triciclo.eco.br\/en\" title=\"In\u00edcio\">In\u00edcio<\/a>\n\t\t<\/span><span class=\"aioseo-breadcrumb-separator\">&raquo;<\/span><span class=\"aioseo-breadcrumb\">\n\t\t\t<a href=\"https:\/\/triciclo.eco.br\/en\/category\/blog\/\" title=\"Blog\">Blog<\/a>\n\t\t<\/span><span class=\"aioseo-breadcrumb-separator\">&raquo;<\/span><span class=\"aioseo-breadcrumb\">\n\t\t\tLeroy Merlin firma parceria com Ambipar Triciclo em projeto para o descarte de materiais recicl\u00e1veis\n\t\t<\/span><\/div>","aioseo_breadcrumb_json":[{"label":"In\u00edcio","link":"https:\/\/triciclo.eco.br\/en"},{"label":"Blog","link":"https:\/\/triciclo.eco.br\/en\/category\/blog\/"},{"label":"Leroy Merlin firma parceria com Ambipar Triciclo em projeto para o descarte de materiais recicl\u00e1veis","link":"https:\/\/triciclo.eco.br\/en\/leroy-merlin-firma-parceria-com-ambipar-triciclo-em-projeto-para-o-descarte-de-materiais-reciclaveis\/"}],"jetpack_sharing_enabled":true,"jetpack_featured_media_url":"https:\/\/triciclo.eco.br\/wp-content\/uploads\/2023\/05\/IMG-20230425-WA0030-gigapixel-hq-width-2000px.jpg","_links":{"self":[{"href":"https:\/\/triciclo.eco.br\/en\/wp-json\/wp\/v2\/posts\/230798","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/triciclo.eco.br\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/triciclo.eco.br\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/triciclo.eco.br\/en\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/triciclo.eco.br\/en\/wp-json\/wp\/v2\/comments?post=230798"}],"version-history":[{"count":4,"href":"https:\/\/triciclo.eco.br\/en\/wp-json\/wp\/v2\/posts\/230798\/revisions"}],"predecessor-version":[{"id":230804,"href":"https:\/\/triciclo.eco.br\/en\/wp-json\/wp\/v2\/posts\/230798\/revisions\/230804"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/triciclo.eco.br\/en\/wp-json\/wp\/v2\/media\/230791"}],"wp:attachment":[{"href":"https:\/\/triciclo.eco.br\/en\/wp-json\/wp\/v2\/media?parent=230798"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/triciclo.eco.br\/en\/wp-json\/wp\/v2\/categories?post=230798"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/triciclo.eco.br\/en\/wp-json\/wp\/v2\/tags?post=230798"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}