{"id":225898,"date":"2020-02-20T19:23:15","date_gmt":"2020-02-20T22:23:15","guid":{"rendered":"https:\/\/triciclo.eco.br\/?page_id=225898"},"modified":"2024-05-17T15:11:16","modified_gmt":"2024-05-17T18:11:16","slug":"politica-de-privacidade","status":"publish","type":"page","link":"https:\/\/triciclo.eco.br\/es\/politica-de-privacidade\/","title":{"rendered":"Pol\u00edtica de Privacidade"},"content":{"rendered":"<p>[et_pb_section fb_built=&#8221;1&#8243; _builder_version=&#8221;4.16&#8243; background_enable_image=&#8221;off&#8221; background_size=&#8221;contain&#8221; custom_padding=&#8221;40px||40px||true|false&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_row _builder_version=&#8221;4.16&#8243; min_height=&#8221;88px&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_column type=&#8221;4_4&#8243; _builder_version=&#8221;4.16&#8243; global_colors_info=&#8221;{}&#8221;][et_pb_text _builder_version=&#8221;4.16&#8243; text_text_color=&#8221;#2D2D2D&#8221; text_font_size=&#8221;17px&#8221; header_font=&#8221;Montserrat|300|||||||&#8221; header_text_align=&#8221;center&#8221; header_text_color=&#8221;#C1D32A&#8221; header_font_size=&#8221;42px&#8221; header_line_height=&#8221;1.2em&#8221; custom_margin=&#8221;-20px||||false|false&#8221; custom_padding=&#8221;0px||0px||false|false&#8221; global_colors_info=&#8221;{}&#8221;]<\/p>\n<h1><strong>Pol\u00edtica de Privacidade<\/strong><\/h1>\n<p>[\/et_pb_text][et_pb_text _builder_version=&#8221;4.16&#8243; text_font=&#8221;Lato|300|||||||&#8221; text_text_color=&#8221;#2D2D2D&#8221; text_font_size=&#8221;17px&#8221; text_line_height=&#8221;1.5em&#8221; custom_margin=&#8221;-20px||-3px||false|false&#8221; custom_padding=&#8221;||0px|||&#8221; global_colors_info=&#8221;{}&#8221;]<\/p>\n<p style=\"text-align: center;\"><span style=\"font-size: x-large;\">Consulte aqui a Pol\u00edtica de Privacidade do Programa Triciclo de Fidelidade e Recompensas!<\/span><\/p>\n<p>[\/et_pb_text][\/et_pb_column][\/et_pb_row][\/et_pb_section][et_pb_section fb_built=&#8221;1&#8243; _builder_version=&#8221;4.16&#8243; custom_padding=&#8221;0px|||||&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_row _builder_version=&#8221;4.16&#8243; custom_padding=&#8221;15px|||||&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_column type=&#8221;4_4&#8243; _builder_version=&#8221;4.16&#8243; global_colors_info=&#8221;{}&#8221;][et_pb_text _builder_version=&#8221;4.16&#8243; global_colors_info=&#8221;{}&#8221;]<\/p>\n<div style=\"text-align: center;\">\n<div class=\"app-header\"><strong style=\"font-size: 14px;\">POL\u00cdTICA DE PRIVACIDADE DO SISTEMA TRICICLO DE FIDELIDADE E RECOMPENSAS<\/strong><\/div>\n<div class=\"app-container\">\n<div class=\"bootbox-body\">\n<p>&nbsp;<\/p>\n<p style=\"text-align: justify;\">Para se tornar um Participante do Sistema Triciclo de Fidelidade e Recompensas, a\u00a0<strong><i>(i)<\/i><\/strong>\u00a0pessoa f\u00edsica plenamente capaz, as\u00a0<strong><i>(ii)<\/i><\/strong>\u00a0pessoas f\u00edsicas absolutamente ou relativamente incapazes, por meio de seus respectivos representantes ou assistentes,\u00a0e a <strong><em>(iii) <\/em><\/strong>pessoas jur\u00eddicas, por meio de seus representantes legais, dever\u00e3o informar, obrigatoriamente:<\/p>\n<ol style=\"text-align: justify;\" type=\"a\">\n<li>email;<\/li>\n<li>senha de acesso ao Sistema Triciclo de Fidelidade e Recompensas;<\/li>\n<li>identifica\u00e7\u00e3o de usu\u00e1rio (\u201cusername\u201d ou \u201clogin\u201d); e,<br \/>4. CPF\/CNPJ.<\/li>\n<\/ol>\n<p style=\"text-align: justify;\">facultativamente, ser\u00e3o solicitadas as seguintes informa\u00e7\u00f5es:<\/p>\n<ol style=\"text-align: justify;\" start=\"4\" type=\"a\">\n<li>nome completo;<\/li>\n<li>CEP;<\/li>\n<li>Data de nascimento;<\/li>\n<li>N\u00famero de telefone celular.<\/li>\n<\/ol>\n<p style=\"text-align: justify;\">eventualmente, informa\u00e7\u00f5es adicionais poder\u00e3o ser solicitadas, mormente para resgate de benef\u00edcios, como, por exemplo, n\u00famero de instala\u00e7\u00e3o de conta de luz junto a ENEL e n\u00famero de cart\u00e3o do Bilhete \u00danico.<\/p>\n<p style=\"text-align: justify;\">As informa\u00e7\u00f5es coletadas durante o processo de inscri\u00e7\u00e3o ser\u00e3o utilizadas para garantir a identidade da pessoa como Participante do Sistema Triciclo de Fidelidade e Recompensas, bem como para a realiza\u00e7\u00e3o de estudos de mercado e eventual envio de promo\u00e7\u00f5es\/campanhas publicit\u00e1rias, sempre respeitando as disposi\u00e7\u00f5es da Lei 13.709\/2018 (&#8220;Lei Geral de Prote\u00e7\u00e3o de Dados Pessoais&#8221;).<\/p>\n<p style=\"text-align: justify;\">Oferecemos aos Participantes do Sistema Triciclo de Fidelidade e Recompensas question\u00e1rios opcionais, todavia, n\u00e3o forneceremos suas informa\u00e7\u00f5es pessoais a terceiros. Tamb\u00e9m solicitamos que nossos Participantes nos informem de suas prefer\u00eancias pessoais. As informa\u00e7\u00f5es nesses question\u00e1rios e as suas prefer\u00eancias pessoais ser\u00e3o utilizadas para desenvolver ofertas e promo\u00e7\u00f5es para melhor servir ao Participante. Ocasionalmente, junto com os nossos Parceiros, poderemos oferecer Pontos Triciclo em troca do preenchimento de pesquisas e question\u00e1rios.<\/p>\n<p style=\"text-align: justify;\">Buscando garantir a entrega do pr\u00eamio escolhido pelo Participante, poder\u00e1 ser solicitada a confirma\u00e7\u00e3o de informa\u00e7\u00f5es pessoais que j\u00e1 constem em seu cadastro, como, por exemplo, a senha de acesso. Al\u00e9m disso, para o resgate de determinado pr\u00eamio, poder\u00e3o ser solicitadas informa\u00e7\u00f5es pessoais e espec\u00edficas, necess\u00e1rias ao processo interno para opera\u00e7\u00e3o do pretendido resgate. As informa\u00e7\u00f5es fornecidas durante o processo de resgate ser\u00e3o tamb\u00e9m enviadas diretamente aos Fornecedores, para que estes promovam a entrega (ou cr\u00e9dito) do pretendido pr\u00eamio. Cabem aos Fornecedores do pr\u00eamio, nesse caso, confirmar o recebimento ou entrega do pedido de troca, para fins de localiza\u00e7\u00e3o, quando necess\u00e1rio.<\/p>\n<p style=\"text-align: justify;\">Para garantir a\u00e7\u00f5es relevantes aos Participantes, compartilhamos com nossos parceiros informa\u00e7\u00f5es agrupadas no perfil da base. Entretanto, respeitando a privacidade de nossos Participantes, tais dados n\u00e3o conter\u00e3o informa\u00e7\u00f5es pessoais de identifica\u00e7\u00e3o. A Triciclo n\u00e3o ir\u00e1 vender, trocar, ou veicular as informa\u00e7\u00f5es pessoais de identifica\u00e7\u00e3o dos Participantes para um terceiro sem a devida permiss\u00e3o.<\/p>\n<p style=\"text-align: justify;\">O Sistema Triciclo de Fidelidade e Recompensas, ocasionalmente, enviar\u00e1 emails, SMS ou push\u2019s por meio de aplicativo mobile aos Participantes, comunicando, por exemplo, novas formas de ganhar Pontos, promo\u00e7\u00f5es, oportunidades de troca e o saldo de sua Conta. Voc\u00ea poder\u00e1 optar ou n\u00e3o pelo recebimento de tais comunicados, ativando ou desativando o campo &#8220;Gostaria de receber informa\u00e7\u00f5es sobre o Sistema Triciclo de Fidelidade e Recompensas&#8221; na se\u00e7\u00e3o apropriada existente no site www.triciclo.eco.br, no aplicativo Triciclo ou atrav\u00e9s das pr\u00f3prias Retorna Machine e Recicla Pharma.<\/p>\n<p style=\"text-align: justify;\">Caso esta op\u00e7\u00e3o n\u00e3o seja escolhida no ato de cadastramento do Participante ou n\u00e3o seja selecionada posteriormente, fica entendido que o Participante n\u00e3o se op\u00f5e ao recebimento desses contatos. A desativa\u00e7\u00e3o desta facilidade, por\u00e9m, n\u00e3o isenta o Participante do recebimento de Confirma\u00e7\u00f5es de Troca de Pontos, Confirma\u00e7\u00e3o de solicita\u00e7\u00e3o de Senha, Confirma\u00e7\u00e3o de Altera\u00e7\u00e3o de E-mail ou demais dados de seu cadastro e respostas \u00e0s requisi\u00e7\u00f5es enviadas via servi\u00e7os de atendimento ao Participante.<\/p>\n<p style=\"text-align: justify;\">Todos os dados fornecidos ao Sistema Triciclo de Fidelidade e Recompensas estar\u00e3o sob medidas de seguran\u00e7a para assegurar a privacidade do Participante e autenticidade do cadastro efetuado, de maneira a evitar ao m\u00e1ximo poss\u00edvel a interfer\u00eancia, intercepta\u00e7\u00e3o ou acesso destes dados por terceiros.<\/p>\n<p style=\"text-align: justify;\">Cabe ao Participante, ou seu respectivo representante ou assistente, quando for o caso, a responsabilidade de manter as informa\u00e7\u00f5es cadastrais e de acesso ao Sistema Triciclo de Fidelidade e Recompensas devidamente atualizadas e em sigilo, n\u00e3o compartilhando a senha pessoal com terceiros.<\/p>\n<p style=\"text-align: justify;\">O Sistema Triciclo de Fidelidade e Recompensas poder\u00e1 utilizar ferramentas conhecidas como &#8220;cookies&#8221;, que permitem a identifica\u00e7\u00e3o do Participante \u00e0 medida que o mesmo visite o site da Triciclo (www.triciclo.eco.br), da Retorna Machine (www.retornamachine.eco.br), da Recicla Pharma (www.reciclapharma.eco.br) e do Deixaki (www.deixaki.eco.br). Com isto, evita-se que o Participante forne\u00e7a novamente seus dados de identifica\u00e7\u00e3o para acesso em cada p\u00e1gina diferente dos sites. Uma vez encerrado o navegador de internet, os cookies ficar\u00e3o sem efeito.<\/p>\n<p style=\"text-align: justify;\">Eventualmente, outros sites e parceiros poder\u00e3o colocar an\u00fancios nas p\u00e1ginas do site da Triciclo, Retorna Machine, Recicla Pharma e\/ou Deixaki, os quais poder\u00e3o tamb\u00e9m trabalhar com a ferramenta \u201ccookies\u201d. Nesse caso, \u00e0 medida que o Participante clica em tais an\u00fancios ou verifica seu conte\u00fado, estar\u00e1 o mesmo saindo do endere\u00e7o eletr\u00f4nico da da Triciclo, Retorna Machine, Recicla Pharma e\/ou Deixaki. Neste momento, a coleta de informa\u00e7\u00f5es n\u00e3o est\u00e1 mais sob a responsabilidade de Triciclo, raz\u00e3o pela qual n\u00e3o cabe \u00e0 Triciclo qualquer garantia de que tais sites n\u00e3o utilizar\u00e3o os cookies obtidos por meio do link; raz\u00e3o pela qual recomendamos que, neste caso, os Participantes realizem verifica\u00e7\u00f5es junto ao respectivo provedor do conte\u00fado em quest\u00e3o, caso tenham perguntas sobre o uso das informa\u00e7\u00f5es de tais cookies.<\/p>\n<p style=\"text-align: justify;\">Para sugest\u00f5es e\/ou d\u00favidas, poder\u00e1 o interessado ou o Participante entrar em contato com a Triciclo, atrav\u00e9s:<\/p>\n<ol type=\"a\">\n<li style=\"text-align: justify;\">Servi\u00e7o de Apoio ao Consumidor &#8211; SAC: 0800 880 9999;<\/li>\n<li style=\"text-align: justify;\">www.triciclo.eco.br; ou<\/li>\n<li style=\"text-align: justify;\">contato.triciclo@ambipar.com<\/li>\n<\/ol>\n<\/div>\n<\/div>\n<\/div>\n<p>[\/et_pb_text][\/et_pb_column][\/et_pb_row][\/et_pb_section]<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Pol\u00edtica de Privacidade Consulte aqui a Pol\u00edtica de Privacidade do Programa Triciclo de Fidelidade e Recompensas! POL\u00cdTICA DE PRIVACIDADE DO SISTEMA TRICICLO DE FIDELIDADE E RECOMPENSAS &nbsp; Para se tornar um Participante do Sistema Triciclo de Fidelidade e Recompensas, a\u00a0(i)\u00a0pessoa f\u00edsica plenamente capaz, as\u00a0(ii)\u00a0pessoas f\u00edsicas absolutamente ou relativamente incapazes, por meio de seus respectivos representantes [&hellip;]<\/p>\n","protected":false},"author":6,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_et_pb_use_builder":"on","_et_pb_old_content":"","_et_gb_content_width":"","footnotes":""},"class_list":["post-225898","page","type-page","status-publish","hentry"],"aioseo_notices":[],"aioseo_head":"\n\t\t<!-- All in One SEO 5.0.0.1 - aioseo.com -->\n\t<meta name=\"description\" content=\"Pol\u00edtica de Privacidade Consulte aqui a Pol\u00edtica de Privacidade do Programa Triciclo de Fidelidade e Recompensas! POL\u00cdTICA DE PRIVACIDADE DO SISTEMA TRICICLO DE FIDELIDADE E RECOMPENSAS Para se tornar um Participante do Sistema Triciclo de Fidelidade e Recompensas, a (i) pessoa f\u00edsica plenamente capaz, as (ii) pessoas f\u00edsicas absolutamente ou relativamente incapazes, por meio de seus respectivos representantes\" \/>\n\t<meta name=\"robots\" content=\"max-image-preview:large\" \/>\n\t<link rel=\"canonical\" href=\"https:\/\/triciclo.eco.br\/es\/politica-de-privacidade\/\" \/>\n\t<meta name=\"generator\" content=\"All in One SEO (AIOSEO) 5.0.0.1\" \/>\n\t\t<meta property=\"og:locale\" content=\"es_ES\" \/>\n\t\t<meta property=\"og:site_name\" content=\"Ambipar Triciclo - Solu\u00e7\u00f5es Sustent\u00e1veis\" \/>\n\t\t<meta property=\"og:type\" content=\"article\" \/>\n\t\t<meta property=\"og:title\" content=\"Pol\u00edtica de Privacidade - Ambipar Triciclo\" \/>\n\t\t<meta property=\"og:description\" content=\"Pol\u00edtica de Privacidade Consulte aqui a Pol\u00edtica de Privacidade do Programa Triciclo de Fidelidade e Recompensas! POL\u00cdTICA DE PRIVACIDADE DO SISTEMA TRICICLO DE FIDELIDADE E RECOMPENSAS Para se tornar um Participante do Sistema Triciclo de Fidelidade e Recompensas, a (i) pessoa f\u00edsica plenamente capaz, as (ii) pessoas f\u00edsicas absolutamente ou relativamente incapazes, por meio de seus respectivos representantes\" \/>\n\t\t<meta property=\"og:url\" content=\"https:\/\/triciclo.eco.br\/es\/politica-de-privacidade\/\" \/>\n\t\t<meta property=\"og:image\" content=\"https:\/\/triciclo.eco.br\/wp-content\/uploads\/2023\/08\/triciclo-logo-1.png\" \/>\n\t\t<meta property=\"og:image:secure_url\" content=\"https:\/\/triciclo.eco.br\/wp-content\/uploads\/2023\/08\/triciclo-logo-1.png\" \/>\n\t\t<meta property=\"og:image:width\" content=\"200\" \/>\n\t\t<meta property=\"og:image:height\" content=\"200\" \/>\n\t\t<meta property=\"article:published_time\" content=\"2020-02-20T22:23:15+00:00\" \/>\n\t\t<meta property=\"article:modified_time\" content=\"2024-05-17T18:11:16+00:00\" \/>\n\t\t<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/ambipar.triciclo\" \/>\n\t\t<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n\t\t<meta name=\"twitter:site\" content=\"@AmbiparTriciclo\" \/>\n\t\t<meta name=\"twitter:title\" content=\"Pol\u00edtica de Privacidade - Ambipar Triciclo\" \/>\n\t\t<meta name=\"twitter:description\" content=\"Pol\u00edtica de Privacidade Consulte aqui a Pol\u00edtica de Privacidade do Programa Triciclo de Fidelidade e Recompensas! POL\u00cdTICA DE PRIVACIDADE DO SISTEMA TRICICLO DE FIDELIDADE E RECOMPENSAS Para se tornar um Participante do Sistema Triciclo de Fidelidade e Recompensas, a (i) pessoa f\u00edsica plenamente capaz, as (ii) pessoas f\u00edsicas absolutamente ou relativamente incapazes, por meio de seus respectivos representantes\" \/>\n\t\t<meta name=\"twitter:creator\" content=\"@AmbiparTriciclo\" \/>\n\t\t<meta name=\"twitter:image\" content=\"https:\/\/triciclo.eco.br\/wp-content\/uploads\/2023\/08\/Triciclo.jpg\" \/>\n\t\t<script type=\"application\/ld+json\" class=\"aioseo-schema\">\n\t\t\t{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/triciclo.eco.br\\\/es\\\/politica-de-privacidade\\\/#breadcrumblist\",\"itemListElement\":[{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/triciclo.eco.br\\\/es#listItem\",\"position\":1,\"name\":\"In\\u00edcio\",\"item\":\"https:\\\/\\\/triciclo.eco.br\\\/es\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/triciclo.eco.br\\\/es\\\/politica-de-privacidade\\\/#listItem\",\"name\":\"Pol\\u00edtica de Privacidade\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/triciclo.eco.br\\\/es\\\/politica-de-privacidade\\\/#listItem\",\"position\":2,\"name\":\"Pol\\u00edtica de Privacidade\",\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/triciclo.eco.br\\\/es#listItem\",\"name\":\"In\\u00edcio\"}}]},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/triciclo.eco.br\\\/es\\\/#organization\",\"name\":\"Ambipar Triciclo Solu\\u00e7\\u00f5es Sustent\\u00e1veis\",\"description\":\"Solu\\u00e7\\u00f5es Sustent\\u00e1veis\",\"url\":\"https:\\\/\\\/triciclo.eco.br\\\/es\\\/\",\"telephone\":\"+551134295050\",\"logo\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/triciclo.eco.br\\\/wp-content\\\/uploads\\\/2023\\\/08\\\/Triciclo.jpg\",\"@id\":\"https:\\\/\\\/triciclo.eco.br\\\/es\\\/politica-de-privacidade\\\/#organizationLogo\",\"width\":113,\"height\":113},\"image\":{\"@id\":\"https:\\\/\\\/triciclo.eco.br\\\/es\\\/politica-de-privacidade\\\/#organizationLogo\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/ambipar.triciclo\",\"https:\\\/\\\/twitter.com\\\/AmbiparTriciclo\",\"https:\\\/\\\/www.instagram.com\\\/triciclo_retornamachine\\\/\",\"https:\\\/\\\/www.youtube.com\\\/@TricicloSolucoesSustentaveis\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/triciclo-solues-sustentveis\\\/\"]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/triciclo.eco.br\\\/es\\\/politica-de-privacidade\\\/#webpage\",\"url\":\"https:\\\/\\\/triciclo.eco.br\\\/es\\\/politica-de-privacidade\\\/\",\"name\":\"Pol\\u00edtica de Privacidade - Ambipar Triciclo\",\"description\":\"Pol\\u00edtica de Privacidade Consulte aqui a Pol\\u00edtica de Privacidade do Programa Triciclo de Fidelidade e Recompensas! POL\\u00cdTICA DE PRIVACIDADE DO SISTEMA TRICICLO DE FIDELIDADE E RECOMPENSAS Para se tornar um Participante do Sistema Triciclo de Fidelidade e Recompensas, a (i) pessoa f\\u00edsica plenamente capaz, as (ii) pessoas f\\u00edsicas absolutamente ou relativamente incapazes, por meio de seus respectivos representantes\",\"inLanguage\":\"es-ES\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/triciclo.eco.br\\\/es\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/triciclo.eco.br\\\/es\\\/politica-de-privacidade\\\/#breadcrumblist\"},\"datePublished\":\"2020-02-20T19:23:15-03:00\",\"dateModified\":\"2024-05-17T15:11:16-03:00\"},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/triciclo.eco.br\\\/es\\\/#website\",\"url\":\"https:\\\/\\\/triciclo.eco.br\\\/es\\\/\",\"name\":\"Ambipar Triciclo\",\"alternateName\":\"Triciclo\",\"description\":\"Solu\\u00e7\\u00f5es Sustent\\u00e1veis\",\"inLanguage\":\"es-ES\",\"publisher\":{\"@id\":\"https:\\\/\\\/triciclo.eco.br\\\/es\\\/#organization\"}}]}\n\t\t<\/script>\n\t\t<!-- All in One SEO -->\n\n","aioseo_head_json":{"title":"Pol\u00edtica de Privacidade - Ambipar Triciclo","description":"Pol\u00edtica de Privacidade Consulte aqui a Pol\u00edtica de Privacidade do Programa Triciclo de Fidelidade e Recompensas! POL\u00cdTICA DE PRIVACIDADE DO SISTEMA TRICICLO DE FIDELIDADE E RECOMPENSAS Para se tornar um Participante do Sistema Triciclo de Fidelidade e Recompensas, a (i) pessoa f\u00edsica plenamente capaz, as (ii) pessoas f\u00edsicas absolutamente ou relativamente incapazes, por meio de seus respectivos representantes","canonical_url":"https:\/\/triciclo.eco.br\/es\/politica-de-privacidade\/","robots":"max-image-preview:large","keywords":"","webmasterTools":{"miscellaneous":""},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"BreadcrumbList","@id":"https:\/\/triciclo.eco.br\/es\/politica-de-privacidade\/#breadcrumblist","itemListElement":[{"@type":"ListItem","@id":"https:\/\/triciclo.eco.br\/es#listItem","position":1,"name":"In\u00edcio","item":"https:\/\/triciclo.eco.br\/es","nextItem":{"@type":"ListItem","@id":"https:\/\/triciclo.eco.br\/es\/politica-de-privacidade\/#listItem","name":"Pol\u00edtica de Privacidade"}},{"@type":"ListItem","@id":"https:\/\/triciclo.eco.br\/es\/politica-de-privacidade\/#listItem","position":2,"name":"Pol\u00edtica de Privacidade","previousItem":{"@type":"ListItem","@id":"https:\/\/triciclo.eco.br\/es#listItem","name":"In\u00edcio"}}]},{"@type":"Organization","@id":"https:\/\/triciclo.eco.br\/es\/#organization","name":"Ambipar Triciclo Solu\u00e7\u00f5es Sustent\u00e1veis","description":"Solu\u00e7\u00f5es Sustent\u00e1veis","url":"https:\/\/triciclo.eco.br\/es\/","telephone":"+551134295050","logo":{"@type":"ImageObject","url":"https:\/\/triciclo.eco.br\/wp-content\/uploads\/2023\/08\/Triciclo.jpg","@id":"https:\/\/triciclo.eco.br\/es\/politica-de-privacidade\/#organizationLogo","width":113,"height":113},"image":{"@id":"https:\/\/triciclo.eco.br\/es\/politica-de-privacidade\/#organizationLogo"},"sameAs":["https:\/\/www.facebook.com\/ambipar.triciclo","https:\/\/twitter.com\/AmbiparTriciclo","https:\/\/www.instagram.com\/triciclo_retornamachine\/","https:\/\/www.youtube.com\/@TricicloSolucoesSustentaveis","https:\/\/www.linkedin.com\/company\/triciclo-solues-sustentveis\/"]},{"@type":"WebPage","@id":"https:\/\/triciclo.eco.br\/es\/politica-de-privacidade\/#webpage","url":"https:\/\/triciclo.eco.br\/es\/politica-de-privacidade\/","name":"Pol\u00edtica de Privacidade - Ambipar Triciclo","description":"Pol\u00edtica de Privacidade Consulte aqui a Pol\u00edtica de Privacidade do Programa Triciclo de Fidelidade e Recompensas! POL\u00cdTICA DE PRIVACIDADE DO SISTEMA TRICICLO DE FIDELIDADE E RECOMPENSAS Para se tornar um Participante do Sistema Triciclo de Fidelidade e Recompensas, a (i) pessoa f\u00edsica plenamente capaz, as (ii) pessoas f\u00edsicas absolutamente ou relativamente incapazes, por meio de seus respectivos representantes","inLanguage":"es-ES","isPartOf":{"@id":"https:\/\/triciclo.eco.br\/es\/#website"},"breadcrumb":{"@id":"https:\/\/triciclo.eco.br\/es\/politica-de-privacidade\/#breadcrumblist"},"datePublished":"2020-02-20T19:23:15-03:00","dateModified":"2024-05-17T15:11:16-03:00"},{"@type":"WebSite","@id":"https:\/\/triciclo.eco.br\/es\/#website","url":"https:\/\/triciclo.eco.br\/es\/","name":"Ambipar Triciclo","alternateName":"Triciclo","description":"Solu\u00e7\u00f5es Sustent\u00e1veis","inLanguage":"es-ES","publisher":{"@id":"https:\/\/triciclo.eco.br\/es\/#organization"}}]},"og:locale":"es_ES","og:site_name":"Ambipar Triciclo - Solu\u00e7\u00f5es Sustent\u00e1veis","og:type":"article","og:title":"Pol\u00edtica de Privacidade - Ambipar Triciclo","og:description":"Pol\u00edtica de Privacidade Consulte aqui a Pol\u00edtica de Privacidade do Programa Triciclo de Fidelidade e Recompensas! POL\u00cdTICA DE PRIVACIDADE DO SISTEMA TRICICLO DE FIDELIDADE E RECOMPENSAS Para se tornar um Participante do Sistema Triciclo de Fidelidade e Recompensas, a (i) pessoa f\u00edsica plenamente capaz, as (ii) pessoas f\u00edsicas absolutamente ou relativamente incapazes, por meio de seus respectivos representantes","og:url":"https:\/\/triciclo.eco.br\/es\/politica-de-privacidade\/","og:image":"https:\/\/triciclo.eco.br\/wp-content\/uploads\/2023\/08\/triciclo-logo-1.png","og:image:secure_url":"https:\/\/triciclo.eco.br\/wp-content\/uploads\/2023\/08\/triciclo-logo-1.png","og:image:width":200,"og:image:height":200,"article:published_time":"2020-02-20T22:23:15+00:00","article:modified_time":"2024-05-17T18:11:16+00:00","article:publisher":"https:\/\/www.facebook.com\/ambipar.triciclo","twitter:card":"summary_large_image","twitter:site":"@AmbiparTriciclo","twitter:title":"Pol\u00edtica de Privacidade - Ambipar Triciclo","twitter:description":"Pol\u00edtica de Privacidade Consulte aqui a Pol\u00edtica de Privacidade do Programa Triciclo de Fidelidade e Recompensas! POL\u00cdTICA DE PRIVACIDADE DO SISTEMA TRICICLO DE FIDELIDADE E RECOMPENSAS Para se tornar um Participante do Sistema Triciclo de Fidelidade e Recompensas, a (i) pessoa f\u00edsica plenamente capaz, as (ii) pessoas f\u00edsicas absolutamente ou relativamente incapazes, por meio de seus respectivos representantes","twitter:creator":"@AmbiparTriciclo","twitter:image":"https:\/\/triciclo.eco.br\/wp-content\/uploads\/2023\/08\/Triciclo.jpg"},"aioseo_meta_data":{"post_id":"225898","title":null,"description":null,"keywords":[],"keyphrases":{"focus":{"keyphrase":"","score":0,"analysis":{"keyphraseInTitle":{"score":0,"maxScore":9,"error":1}}},"additional":[]},"primary_term":null,"canonical_url":null,"og_title":null,"og_description":null,"og_object_type":"default","og_image_type":"default","og_image_url":null,"og_image_width":null,"og_image_height":null,"og_image_custom_url":null,"og_image_custom_fields":null,"og_video":"","og_custom_url":null,"og_article_section":null,"og_article_tags":[],"twitter_use_og":false,"twitter_card":"default","twitter_image_type":"default","twitter_image_url":null,"twitter_image_custom_url":null,"twitter_image_custom_fields":null,"twitter_title":null,"twitter_description":null,"schema":{"blockGraphs":[],"customGraphs":[],"default":{"data":{"Article":[],"Course":[],"Dataset":[],"FAQPage":[],"Movie":[],"Person":[],"Product":[],"ProductReview":[],"Car":[],"Recipe":[],"Service":[],"SoftwareApplication":[],"WebPage":[]},"graphName":"WebPage","isEnabled":true},"graphs":[]},"schema_type":"default","schema_type_options":null,"pillar_content":false,"robots_default":true,"robots_noindex":false,"robots_noarchive":false,"robots_nosnippet":false,"robots_nofollow":false,"robots_noimageindex":false,"robots_noodp":false,"robots_notranslate":false,"robots_max_snippet":"-1","robots_max_videopreview":"-1","robots_max_imagepreview":"large","priority":null,"frequency":"default","local_seo":null,"breadcrumb_settings":null,"limit_modified_date":false,"ai":null,"created":"2023-08-29 17:32:37","updated":"2025-08-01 15:40:40","focus_keyword":null,"additional_keywords":null,"truseo_locale":null,"seo_analyzer_scan_date":null},"aioseo_breadcrumb":"<div class=\"aioseo-breadcrumbs\"><span class=\"aioseo-breadcrumb\">\n\t\t\t<a href=\"https:\/\/triciclo.eco.br\/es\" title=\"In\u00edcio\">In\u00edcio<\/a>\n\t\t<\/span><span class=\"aioseo-breadcrumb-separator\">&raquo;<\/span><span class=\"aioseo-breadcrumb\">\n\t\t\tPol\u00edtica de Privacidade\n\t\t<\/span><\/div>","aioseo_breadcrumb_json":[{"label":"In\u00edcio","link":"https:\/\/triciclo.eco.br\/es"},{"label":"Pol\u00edtica de Privacidade","link":"https:\/\/triciclo.eco.br\/es\/politica-de-privacidade\/"}],"jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/triciclo.eco.br\/es\/wp-json\/wp\/v2\/pages\/225898","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/triciclo.eco.br\/es\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/triciclo.eco.br\/es\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/triciclo.eco.br\/es\/wp-json\/wp\/v2\/users\/6"}],"replies":[{"embeddable":true,"href":"https:\/\/triciclo.eco.br\/es\/wp-json\/wp\/v2\/comments?post=225898"}],"version-history":[{"count":10,"href":"https:\/\/triciclo.eco.br\/es\/wp-json\/wp\/v2\/pages\/225898\/revisions"}],"predecessor-version":[{"id":231698,"href":"https:\/\/triciclo.eco.br\/es\/wp-json\/wp\/v2\/pages\/225898\/revisions\/231698"}],"wp:attachment":[{"href":"https:\/\/triciclo.eco.br\/es\/wp-json\/wp\/v2\/media?parent=225898"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}