{"id":233125,"date":"2025-08-15T02:05:13","date_gmt":"2025-08-15T05:05:13","guid":{"rendered":"https:\/\/triciclo.eco.br\/?p=233125"},"modified":"2026-05-13T02:16:39","modified_gmt":"2026-05-13T05:16:39","slug":"presenca-ambipar-no-rio-innovation-week-2025","status":"publish","type":"post","link":"https:\/\/triciclo.eco.br\/es\/presenca-ambipar-no-rio-innovation-week-2025\/","title":{"rendered":"Presen\u00e7a Ambipar no Rio Innovation Week 2025"},"content":{"rendered":"<p>[et_pb_section fb_built=&#8221;1&#8243; _builder_version=&#8221;4.16&#8243; global_colors_info=&#8221;{}&#8221;][et_pb_row _builder_version=&#8221;4.20.2&#8243; background_size=&#8221;initial&#8221; background_position=&#8221;top_left&#8221; background_repeat=&#8221;repeat&#8221; width=&#8221;96%&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_column type=&#8221;4_4&#8243; _builder_version=&#8221;4.16&#8243; custom_padding=&#8221;|||&#8221; global_colors_info=&#8221;{}&#8221; custom_padding__hover=&#8221;|||&#8221;][et_pb_text _builder_version=&#8221;4.20.2&#8243; _module_preset=&#8221;default&#8221; text_font=&#8221;Montserrat|700|||||||&#8221; text_font_size=&#8221;22px&#8221; global_colors_info=&#8221;{}&#8221;]<\/p>\n<p>O Rio Innovation Week de 2025 levou a Retorna Machine como solu\u00e7\u00e3o inovadora sustent\u00e1vel<\/p>\n<p>[\/et_pb_text][et_pb_text _builder_version=&#8221;4.20.2&#8243; _module_preset=&#8221;default&#8221; text_font=&#8221;Montserrat||||||||&#8221; text_font_size=&#8221;16px&#8221; global_colors_info=&#8221;{}&#8221;]<\/p>\n<p>Um dos maiores eventos de tecnologia e inova\u00e7\u00e3o da Am\u00e9rica Latina incluiu a solu\u00e7\u00e3o como op\u00e7\u00e3o sustent\u00e1vel tecnol\u00f3gica<\/p>\n<p>[\/et_pb_text][et_pb_text _builder_version=&#8221;4.20.2&#8243; background_size=&#8221;initial&#8221; background_position=&#8221;top_left&#8221; background_repeat=&#8221;repeat&#8221; global_colors_info=&#8221;{}&#8221;]<\/p>\n<p>A Ambipar Triciclo marcou presen\u00e7a no <strong>Rio Innovation Week 2025,<\/strong> um dos maiores eventos de tecnologia e inova\u00e7\u00e3o da Am\u00e9rica Latina, levando solu\u00e7\u00f5es sustent\u00e1veis e experi\u00eancias interativas de reciclagem para o p\u00fablico.<\/p>\n<p>Durante o evento, as Retorna Machines incentivaram o descarte correto de res\u00edduos recicl\u00e1veis de forma pr\u00e1tica e tecnol\u00f3gica, promovendo conscientiza\u00e7\u00e3o ambiental em um ambiente voltado \u00e0 inova\u00e7\u00e3o e transforma\u00e7\u00e3o de neg\u00f3cios.<\/p>\n<p>A participa\u00e7\u00e3o refor\u00e7ou o prop\u00f3sito da Ambipar Triciclo de conectar tecnologia, impacto positivo e sustentabilidade em grandes eventos nacionais.<\/p>\n<p>[\/et_pb_text][\/et_pb_column][\/et_pb_row][et_pb_row _builder_version=&#8221;4.20.2&#8243; _module_preset=&#8221;default&#8221; width=&#8221;auto&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_column type=&#8221;4_4&#8243; _builder_version=&#8221;4.20.2&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221;][difl_imagecarousel use_lightbox=&#8221;on&#8221; use_lightbox_caption=&#8221;on&#8221; vertical_align=&#8221;center&#8221; image_scale=&#8221;on&#8221; image_scale_value=&#8221;1&#8243; content_hover=&#8221;on&#8221; anim_direction=&#8221;center&#8221; admin_label=&#8221;Retorna Machine no Rio Innovation Week 2025&#8243; _builder_version=&#8221;4.20.2&#8243; _module_preset=&#8221;default&#8221; caption_font=&#8221;Montserrat|700|||||||&#8221; caption_text_align=&#8221;center&#8221; caption_text_color=&#8221;#FFFFFF&#8221; locked=&#8221;off&#8221; global_colors_info=&#8221;{}&#8221; ic_overlay_background_bgcolor__hover_enabled=&#8221;on|hover&#8221; ic_overlay_background_bgcolor__hover=&#8221;rgba(0,0,0,0.31)&#8221;][difl_imagecarouselitem admin_label=&#8221;RM Rio Innovation Week 2025 1&#8243; image=&#8221;https:\/\/triciclo.eco.br\/wp-content\/uploads\/2025\/08\/RMRIW202502.jpg&#8221; alt_text=&#8221;Rio Innovation Week 2025&#8243; ic_button_button_url_new_window=&#8221;1&#8243; _builder_version=&#8221;4.20.2&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221;][\/difl_imagecarouselitem][difl_imagecarouselitem admin_label=&#8221;RM Rio Innovation Week 2025 2&#8243; image=&#8221;https:\/\/triciclo.eco.br\/wp-content\/uploads\/2025\/08\/RMRIW202503.jpg&#8221; alt_text=&#8221;Rio Innovation Week 2025&#8243; ic_button_button_url_new_window=&#8221;1&#8243; _builder_version=&#8221;4.20.2&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221;][\/difl_imagecarouselitem][difl_imagecarouselitem admin_label=&#8221;RM Rio Innovation Week 2025 3&#8243; image=&#8221;https:\/\/triciclo.eco.br\/wp-content\/uploads\/2025\/08\/RMRIW202501.jpg&#8221; alt_text=&#8221;Rio Innovation Week 2025&#8243; ic_button_button_url_new_window=&#8221;1&#8243; _builder_version=&#8221;4.20.2&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221;][\/difl_imagecarouselitem][difl_imagecarouselitem admin_label=&#8221;RM Rio Innovation Week 2025 4&#8243; image=&#8221;https:\/\/triciclo.eco.br\/wp-content\/uploads\/2025\/08\/RMRIW202504.jpg&#8221; alt_text=&#8221;Rio Innovation Week 2025&#8243; ic_button_button_url_new_window=&#8221;1&#8243; _builder_version=&#8221;4.20.2&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221;][\/difl_imagecarouselitem][\/difl_imagecarousel][\/et_pb_column][\/et_pb_row][\/et_pb_section]<\/p>\n","protected":false},"excerpt":{"rendered":"<p>O Rio Innovation Week de 2025 levou a Retorna Machine como solu\u00e7\u00e3o inovadora sustent\u00e1velUm dos maiores eventos de tecnologia e inova\u00e7\u00e3o da Am\u00e9rica Latina incluiu a solu\u00e7\u00e3o como op\u00e7\u00e3o sustent\u00e1vel tecnol\u00f3gicaA Ambipar Triciclo marcou presen\u00e7a no Rio Innovation Week 2025, um dos maiores eventos de tecnologia e inova\u00e7\u00e3o da Am\u00e9rica Latina, levando solu\u00e7\u00f5es sustent\u00e1veis e [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":233137,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_et_pb_use_builder":"on","_et_pb_old_content":"<p>\"S\u00f3 um coletivo organizado de institui\u00e7\u00f5es p\u00fablicas e privadas, com a colabora\u00e7\u00e3o de pessoas atuantes, \u00e9 capaz de criar uma onda de restaura\u00e7\u00e3o em larga escala no pa\u00eds.\"<\/p><p>O Restaura Brasil \u00e9 uma campanha da The Nature Conservancy (TNC) para mobilizar pessoas e empresas em um movimento coletivo para restaurar 1 bilh\u00e3o de \u00e1rvores no pa\u00eds at\u00e9 2030 e contribuir para que o governo brasileiro alcance sua meta de mitiga\u00e7\u00e3o \u00e0s mudan\u00e7as clim\u00e1ticas no Acordo de Paris.<\/p><p>A restaura\u00e7\u00e3o florestal \u00e9 uma das maiores oportunidade para minimizar as mudan\u00e7as clim\u00e1ticas. Temos que limitar o aumento da temperatura terrestre at\u00e9 1,5\u00baC.<\/p><p>POR QUE RESTAURAR ?<br \/>A vegeta\u00e7\u00e3o natural tem um papel essencial no ciclo da \u00e1gua e na estabiliza\u00e7\u00e3o clim\u00e1tica, al\u00e9m de fornecer alimento, mat\u00e9ria-prima para diversos setores e um ambiente rico em plantas e animais. Para alcan\u00e7ar os compromissos do pa\u00eds no Acordo de Paris \u00e9 preciso acelerar a restaura\u00e7\u00e3o florestal no Brasil, com o engajamento de toda a sociedade.<\/p><p>A The Nature Conservancy (TNC) ajudou na formula\u00e7\u00e3o da pol\u00edtica e do plano nacional de restaura\u00e7\u00e3o da vegeta\u00e7\u00e3o nativa (PLANAVEG) e foi eleita uma das quatro institui\u00e7\u00f5es da sociedade civil a compor o Comit\u00ea Nacional para Recupera\u00e7\u00e3o da Vegeta\u00e7\u00e3o Nativa.<\/p>","_et_gb_content_width":"","_jetpack_memberships_contains_paid_content":false,"footnotes":""},"categories":[8],"tags":[262,62,279,278,277,280],"class_list":["post-233125","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-blog","tag-262","tag-retorna-machine","tag-rio-de-janeiro","tag-rio-innovation-week","tag-rio-innovation-week-2025","tag-tecnologia"],"aioseo_notices":[],"jetpack_featured_media_url":"https:\/\/triciclo.eco.br\/wp-content\/uploads\/2025\/08\/RMRIW2025-CAPA.jpg","jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/triciclo.eco.br\/es\/wp-json\/wp\/v2\/posts\/233125","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/triciclo.eco.br\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/triciclo.eco.br\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/triciclo.eco.br\/es\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/triciclo.eco.br\/es\/wp-json\/wp\/v2\/comments?post=233125"}],"version-history":[{"count":6,"href":"https:\/\/triciclo.eco.br\/es\/wp-json\/wp\/v2\/posts\/233125\/revisions"}],"predecessor-version":[{"id":233139,"href":"https:\/\/triciclo.eco.br\/es\/wp-json\/wp\/v2\/posts\/233125\/revisions\/233139"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/triciclo.eco.br\/es\/wp-json\/wp\/v2\/media\/233137"}],"wp:attachment":[{"href":"https:\/\/triciclo.eco.br\/es\/wp-json\/wp\/v2\/media?parent=233125"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/triciclo.eco.br\/es\/wp-json\/wp\/v2\/categories?post=233125"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/triciclo.eco.br\/es\/wp-json\/wp\/v2\/tags?post=233125"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}